{"id":271,"date":"2023-11-07T22:12:22","date_gmt":"2023-11-07T22:12:22","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/"},"modified":"2023-12-06T11:37:44","modified_gmt":"2023-12-06T11:37:44","slug":"extrair-ano-mes","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/","title":{"rendered":"Como extrair o ano ou m\u00eas de uma data?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-2443841638\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-2911567813\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>Ao trabalhar no Excel, pode ser necess\u00e1rio obter o ano apenas a partir de uma data. Bem, existe uma f\u00f3rmula simples que voc\u00ea pode usar para fazer isso. Neste tutorial, buscaremos extrair um ano ou um m\u00eas de uma data no Excel. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74940\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png\" sizes=\"auto, \" srcset=\"\" alt=\"ano a partir da data\" width=\"473\" height=\"270\"><\/figure><\/div><h2 class=\"wp-block-heading\"> Extraia o ano de uma data<\/h2><p> Para obter o ano a partir da data na c\u00e9lula A1, siga estas etapas:<\/p><ol type=\"1\"><li> Primeiro, <a href=\"https:\/\/exceladvisor.org\/pt\/editar-celula\/\">edite a c\u00e9lula B1<\/a> e insira \u201c=\u201d.<\/li><li> Depois disso, insira a fun\u00e7\u00e3o ANO e os par\u00eanteses iniciais.<\/li><li> Agora consulte a c\u00e9lula A1 onde voc\u00ea tem a data.<\/li><li> No final, insira par\u00eanteses de fechamento e pressione Enter para obter o resultado. <\/li><\/ol><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74941\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/2-extraire-lannee-a-partir-de-la-date.png\" sizes=\"auto, \" srcset=\"\" alt=\"extrato-ano-desde-data\" width=\"266\" height=\"101\"><\/figure><\/div><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=YEAR(A1)<\/code><\/pre><h2 class=\"wp-block-heading\"> Extraia o m\u00eas de uma data<\/h2><p> Se voc\u00ea tiver uma data na c\u00e9lula A1 e quiser extrair o m\u00eas dela, siga estas etapas:<\/p><ol><li> Primeiro, na c\u00e9lula B1, digite \u201c=\u201d.<\/li><li> Depois disso, entre na fun\u00e7\u00e3o M\u00caS e inicie os par\u00eanteses.<\/li><li> Agora consulte a c\u00e9lula A1 onde voc\u00ea tem a data.<\/li><li> No final, insira par\u00eanteses de fechamento e pressione Enter para obter o resultado. <\/li><\/ol><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74942\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/3-extrait-mois-a-partir-de-la-date.png\" sizes=\"auto, \" srcset=\"\" alt=\"extrair do m\u00eas a partir da data\" width=\"501\" height=\"251\"><\/figure><\/div><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=MONTH(A1)<\/code><\/pre><h2 class=\"wp-block-heading\"> Use a fun\u00e7\u00e3o TEXT para obter o ano ou m\u00eas a partir da data<\/h2><p> Al\u00e9m das fun\u00e7\u00f5es que discutimos acima, voc\u00ea pode usar TEXT para obter o ano e o m\u00eas a partir da data. Na fun\u00e7\u00e3o de texto voc\u00ea tem dois argumentos para definir, o primeiro \u00e9 a data e o segundo \u00e9 o format_text que voc\u00ea deseja extrair da data.<\/p><p> No exemplo a seguir, voc\u00ea tem a fun\u00e7\u00e3o de texto com text_format &#8220;AAAA&#8221; que retorna o ano em quatro d\u00edgitos. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74943\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/4-fonction-de-texte-pour-obtenir-lannee.png\" sizes=\"auto, \" srcset=\"\" alt=\"fun\u00e7\u00e3o de texto para obter ano\" width=\"478\" height=\"227\"><\/figure><\/div><p> E se quiser obter um ano de dois d\u00edgitos, voc\u00ea pode usar o seguinte format_text. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74944\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/5-fonction-de-texte-annee-a-deux-chiffres.png\" sizes=\"auto, \" srcset=\"\" alt=\"fun\u00e7\u00e3o de texto-ano de dois d\u00edgitos\" width=\"472\" height=\"273\"><\/figure><\/div><p> Da mesma forma, voc\u00ea pode usar o format_text \u201cMMM\u201d para obter o valor do m\u00eas a partir da data. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74945\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/6-fonction-de-texte-pour-obtenir-le-mois.png\" sizes=\"auto, \" srcset=\"\" alt=\"fun\u00e7\u00e3o de texto para obter o m\u00eas\" width=\"472\" height=\"275\"><\/figure><\/div><p> Para obter um m\u00eas no nome completo. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74946\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/7-mois-complet.png\" sizes=\"auto, \" srcset=\"\" alt=\"nome do m\u00eas completo\" width=\"482\" height=\"252\"><\/figure><\/div><p> E para obter apenas o n\u00famero no resultado. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74947\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/8-obtenir-le-mois-en-nombre.png\" sizes=\"auto, \" srcset=\"\" alt=\"obter m\u00eas como n\u00famero\" width=\"474\" height=\"246\"><\/figure><\/div><h2 class=\"wp-block-heading\"> Use formata\u00e7\u00e3o personalizada Obtenha um ano ou m\u00eas em uma data<\/h2><p> Voc\u00ea tamb\u00e9m pode usar formata\u00e7\u00e3o personalizada para converter uma data em ano ou m\u00eas. Este m\u00e9todo exibe apenas o ano ou m\u00eas de uma data que voc\u00ea possui na c\u00e9lula. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74948\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/9-formatage-personnalise-pour-obtenir-lannee.png\" sizes=\"auto, \" srcset=\"\" alt=\"formata\u00e7\u00e3o personalizada para obter o ano\" width=\"641\" height=\"391\"><\/figure><\/div><ol type=\"1\"><li> Selecione a c\u00e9lula ou intervalo de c\u00e9lulas onde as datas est\u00e3o localizadas.<\/li><li> Abra as op\u00e7\u00f5es de formato <a href=\"https:\/\/exceladvisor.org\/pt\/abrir-opcoes-de-formato-de-celula\/\">usando Ctrl + 1<\/a> .<\/li><li> Clique na op\u00e7\u00e3o Personalizado e a seguir clique no tipo de barra de entrada \u201cAAAA\u201d.<\/li><li> E ent\u00e3o clique em OK.<\/li><\/ol><p> No momento em que voc\u00ea clica em OK, ele mostra o ano em vez da data inteira. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74949\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/10-annee-de-spectacle-seulement.png\" sizes=\"auto, \" srcset=\"\" alt=\"apenas ano de exibi\u00e7\u00e3o\" width=\"380\" height=\"264\"><\/figure><\/div><p> E da mesma forma, voc\u00ea pode inserir o formato do m\u00eas na barra de entrada \u201cTipo\u201d para exibir o m\u00eas em vez da data. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74950\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/11-saisir-le-mois-dans-la-barre-de-saisie.png\" sizes=\"auto, \" srcset=\"\" alt=\"insira o m\u00eas na barra de entrada\" width=\"619\" height=\"367\"><\/figure><\/div><div class=\"gb-container gb-container-52dfcee1 gb-container-sample-file\"><h2 class=\"gb-headline gb-headline-e289c143 gb-headline-text gb-headline-4f7959c2\"> Obtenha o arquivo Excel<\/h2><p> <a class=\"gb-button gb-button-e88d6bee gb-button-text gb-button-button1\" href=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/extraire-lannee.xlsx\" rel=\"nofollow\">Download<\/a><\/p><\/div><div class=\"gb-container gb-container-0df56012 gb-container-mt\"> <a class=\"gb-button gb-button-f9f432f4 gb-button-text gb-button-mt-button\" href=\"https:\/\/exceladvisor.org\/pt\/formulas\/\">Lista de f\u00f3rmulas do Excel<\/a><h2 class=\"gb-headline gb-headline-233444e8 gb-headline-text gb-headline-mt-heading\"> F\u00f3rmulas relacionadas <\/h2><div class=\"gb-grid-wrapper gb-grid-wrapper-a16fa65c gb-grid-wrapper-mt-grid\"><div class=\"gb-grid-column gb-grid-column-50d07e0d\"><div class=\"gb-container gb-container-50d07e0d\"><ul><li> <a href=\"https:\/\/exceladvisor.org\/pt\/adicionar-anos-ate-a-data\/\">Adicione anos atualizados no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-os-anos-entre-duas-datas\/\">Conte anos entre duas datas no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/obter-o-numero-do-dia-do-ano\/\">Obtenha o n\u00famero de dias do ano no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/ganhe-2-anos-de-servico\/\">Obtenha anos de servi\u00e7o no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/anos-entre-datas\/\">Anos entre datas no Excel<\/a> <\/li><\/ul><\/div><\/div><div class=\"gb-grid-column gb-grid-column-5b4a0cf9\"><div class=\"gb-container gb-container-5b4a0cf9\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-271","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como extrair o ano ou m\u00eas de uma data? (Guia 2023)<\/title>\n<meta name=\"description\" content=\"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como extrair o ano ou m\u00eas de uma data? (Guia 2023)\" \/>\n<meta property=\"og:description\" content=\"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:37:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/\",\"name\":\"Como extrair o ano ou m\u00eas de uma data? (Guia 2023)\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png\",\"datePublished\":\"2023-11-07T22:12:22+00:00\",\"dateModified\":\"2023-12-06T11:37:44+00:00\",\"description\":\"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como extrair o ano ou m\u00eas de uma data?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como extrair o ano ou m\u00eas de uma data? (Guia 2023)","description":"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/","og_locale":"pt_PT","og_type":"article","og_title":"Como extrair o ano ou m\u00eas de uma data? (Guia 2023)","og_description":"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas","og_url":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:37:44+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/","url":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/","name":"Como extrair o ano ou m\u00eas de uma data? (Guia 2023)","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png","datePublished":"2023-11-07T22:12:22+00:00","dateModified":"2023-12-06T11:37:44+00:00","description":"Neste tutorial de f\u00f3rmula, aprenderemos como extrair um ano ou m\u00eas de um valor de data. Aprenderemos tr\u00eas","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-an-a-compter-de-la-date.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/extrair-ano-mes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como extrair o ano ou m\u00eas de uma data?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/271\/revisions"}],"predecessor-version":[{"id":1064,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/271\/revisions\/1064"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}