{"id":351,"date":"2023-11-01T06:50:26","date_gmt":"2023-11-01T06:50:26","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/"},"modified":"2023-12-06T11:51:05","modified_gmt":"2023-12-06T11:51:05","slug":"tabela-dinamica-3","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/","title":{"rendered":"Mais de 100 truques ocultos de tabela din\u00e2mica"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-3677173975\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-3284626181\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>Tabelas Din\u00e2micas \u00e9 uma das <a href=\"https:\/\/exceladvisor.org\/pt\/habilidades-de-excelencia\/\"><strong>habilidades intermedi\u00e1rias do Excel<\/strong><\/a> e este \u00e9 um tutorial avan\u00e7ado de Tabelas Din\u00e2micas que mostra as 100 principais dicas e truques para dominar essa habilidade. O fato \u00e9 que, quando se trata de an\u00e1lise de dados, cria\u00e7\u00e3o de relat\u00f3rios r\u00e1pidos e eficientes ou apresenta\u00e7\u00e3o de dados resumidos, nada se compara a uma tabela din\u00e2mica.<\/p><p> Ele \u00e9 din\u00e2mico e flex\u00edvel. Mesmo se voc\u00ea comparar f\u00f3rmulas e tabelas din\u00e2micas, descobrir\u00e1 que as tabelas din\u00e2micas s\u00e3o f\u00e1ceis de usar e gerenciar. Se voc\u00ea quiser usar suas habilidades em tabelas din\u00e2micas, a melhor maneira \u00e9 ter uma lista de dicas e truques que voc\u00ea pode aprender.<\/p><p class=\"grey-note\"> Ao longo desta lista usei as palavras \u201cAnalyze Tab\u201d e \u201cDesign Tab\u201d. Para obter essas duas guias na faixa do Excel, primeiro voc\u00ea deve selecionar uma Tabela Din\u00e2mica. Al\u00e9m disso <a href=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/donnees-des-conseils-de-pivot.xlsx\" rel=\"nofollow\">, certifique-se de baixar este arquivo de amostra<\/a> aqui para tentar esses truques. <\/p><div class=\"wp-block-group more-box is-layout-constrained\"><div class=\"wp-block-group__inner-container\"><h2 class=\"wp-block-heading\"> 5 coisas a considerar antes de criar uma tabela din\u00e2mica<\/h2><p> Antes de criar uma tabela din\u00e2mica, voc\u00ea deve dedicar alguns minutos trabalhando na fonte de dados que usar\u00e1 para verificar se h\u00e1 alguma corre\u00e7\u00e3o que precise ser feita.<\/p><h3 class=\"wp-block-heading\"> 1. Sem colunas e linhas vazias nos dados de origem<\/h3><p> Uma das coisas que voc\u00ea precisa controlar nos dados de origem \u00e9 que n\u00e3o deve haver linhas ou colunas vazias.<\/p><p> Ao criar uma tabela din\u00e2mica, se voc\u00ea tiver uma linha ou coluna em branco, o Excel levar\u00e1 apenas os dados at\u00e9 essa linha ou coluna. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png\" sizes=\"\" srcset=\"\" alt=\"tabelas din\u00e2micas Dicas e truques do Excel para remover linhas e colunas embaladas dos dados de origem\"><\/figure><\/div><h3 class=\"wp-block-heading\"> 2. Nenhuma c\u00e9lula em branco na coluna de valor<\/h3><p> Al\u00e9m da linha e coluna vazias, voc\u00ea n\u00e3o deve ter uma c\u00e9lula vazia na coluna onde est\u00e3o os valores. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableaux-croises-dynamiques-trucs-et-astuces-pour-quil-ne-devrait-pas-y-avoir-de-cellule-vide-dans-la-colonne-de-valeur-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas e truques de tabelas din\u00e2micas do Excel para que n\u00e3o haja c\u00e9lulas em branco na coluna de valor\"><\/figure><\/div><p> O principal motivo para verificar isso \u00e9 que se voc\u00ea tiver uma c\u00e9lula em branco na coluna do campo Valores: o Excel aplicar\u00e1 o n\u00famero no piv\u00f4 em vez da SOMA dos valores.<\/p><h3 class=\"wp-block-heading\"> 3. Os dados devem estar no formato correto<\/h3><p> Ao usar dados de origem para uma tabela din\u00e2mica, eles devem estar no formato correto.<\/p><p> Digamos que voc\u00ea tenha datas em uma coluna e essa coluna esteja formatada como texto. Nesse caso, n\u00e3o seria poss\u00edvel <a href=\"https:\/\/exceladvisor.org\/pt\/datas-do-grupo\/\">agrupar as datas na tabela din\u00e2mica<\/a> que voc\u00ea criou. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Les-trucs-et-astuces-des-tableaux-croises-dynamiques-Excel-pour-le-format-des-donnees-devraient-etre-corrects-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas e truques de tabelas din\u00e2micas do Excel para formato de dados devem estar corretos\"><\/figure><\/div><h3 class=\"wp-block-heading\"> 4. Use uma tabela para dados de origem<\/h3><p> Antes de criar uma tabela din\u00e2mica, voc\u00ea deve converter os dados de origem em uma tabela. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-tableau-croise-dynamique-conseils-astuces-appliquer-le-tableau-aux-donnees-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para inserir uma tabela din\u00e2mica\"><\/figure><\/div><p> Uma tabela se expande cada vez que voc\u00ea adiciona novos dados a ela e isso facilita <a href=\"https:\/\/exceladvisor.org\/pt\/faixa-de-atualizacao-automatica\/\">a altera\u00e7\u00e3o da fonte de dados da tabela din\u00e2mica<\/a> (quase autom\u00e1tica).<\/p><p> Aqui est\u00e3o as etapas:<\/p><ol><li> Selecione todos os seus dados ou uma das c\u00e9lulas.<\/li><li> Pressione a tecla de atalho Ctrl + T.<\/li><li> Clique OK.<\/li><\/ol><h3 class=\"wp-block-heading\"> 5. Remova totais de dados<\/h3><p> Por fim, certifique-se de excluir o total da fonte de dados. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableaux-croises-dynamiques-trucs-et-astuces-pour-supprimer-le-total-des-donnees-source-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas e truques de tabelas din\u00e2micas do Excel para remover o total dos dados de origem\"><\/figure><\/div><p> Se voc\u00ea tiver dados de origem com totais gerais, o Excel considerar\u00e1 esses totais como valores e os valores da tabela din\u00e2mica ser\u00e3o aumentados em dobro.<\/p><p class=\"qt-tip\"> Dica: Se voc\u00ea aplicou uma tabela na fonte de dados, o Excel n\u00e3o incluir\u00e1 esse total ao criar uma tabela din\u00e2mica.<\/p><\/div><\/div><h2 class=\"wp-block-heading\"> Dicas para ajud\u00e1-lo ao criar uma tabela din\u00e2mica<\/h2><p> Agora, essas dicas voc\u00ea pode usar quando os dados estiverem preparados e voc\u00ea estiver pronto para criar uma tabela din\u00e2mica com eles. <\/p><div id=\"ub-content-toggle-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 1. Tabelas din\u00e2micas recomendadas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma op\u00e7\u00e3o na aba \u201cInserir\u201d para verificar as tabelas din\u00e2micas recomendadas. Quando voc\u00ea clica em \u201cTabelas Din\u00e2micas Recomendadas\u201d, ele mostra um conjunto de tabelas din\u00e2micas que podem ser poss\u00edveis com os dados que voc\u00ea possui. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-loption-de-pivot-recommandee-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para criar uma tabela din\u00e2mica usando a op\u00e7\u00e3o din\u00e2mica recomendada\"><\/figure><\/div><p> Esta op\u00e7\u00e3o \u00e9 muito \u00fatil quando voc\u00ea deseja ver todas as possibilidades que tem com os dados dispon\u00edveis. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 2. Criando uma tabela din\u00e2mica a partir de uma an\u00e1lise r\u00e1pida <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma ferramenta no Excel chamada \u201cAn\u00e1lise R\u00e1pida\u201d que se parece com uma barra de ferramentas r\u00e1pida que aparece toda vez que voc\u00ea seleciona o intervalo de dados.<\/p><p> E a partir desta ferramenta voc\u00ea tamb\u00e9m pode criar uma tabela din\u00e2mica.<\/p><p> Ferramenta de an\u00e1lise r\u00e1pida \u279c Tabelas \u279c Tabela din\u00e2mica vazia. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-loutil-danalyse-rapide-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para criar uma tabela din\u00e2mica usando a ferramenta de an\u00e1lise r\u00e1pida\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 3. Pasta de trabalho externa como fonte para tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Esta \u00e9 uma das dicas de tabela din\u00e2mica mais \u00fateis desta lista que quero que voc\u00ea comece a usar agora.<\/p><p> Digamos que voc\u00ea queira dinamizar a partir de uma pasta de trabalho que est\u00e1 em uma pasta diferente e n\u00e3o queira adicionar dados dessa pasta de trabalho \u00e0 sua planilha atual.<\/p><p> Voc\u00ea pode vincular este arquivo como fonte sem adicionar nenhum dado no arquivo atual. Aqui est\u00e3o as etapas.<\/p><ul><li> Na caixa de di\u00e1logo Criar Tabela Din\u00e2mica, selecione &#8220;Usar fonte de dados externa&#8221;. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-selectionner-une-source-de-donnees-externe-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para selecionar uma fonte de dados externa\" width=\"402\" height=\"361\"><\/figure><\/div><ul><li> Depois disso, v\u00e1 at\u00e9 a aba Conex\u00f5es e clique em \u201cProcurar mais\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-cliquer-sur-plus-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para clicar mais\"><\/figure><\/div><ul><li> Localize o arquivo que deseja usar e selecione-o.<\/li><li> Clique OK.<\/li><li> Agora selecione a planilha na qual voc\u00ea possui dados. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-selectionner-selectionner-une-feuille-de-calcul-1.png\" sizes=\"\" srcset=\"\" alt=\"dicas de tabela din\u00e2mica do Excel dicas para selecionar uma planilha\"><\/figure><\/div><ul><li> Clique em OK (duas vezes). <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-tableau-croise-dynamique-conseils-astuces-pour-fichier-est-connecte-1.png\" sizes=\"\" srcset=\"\" alt=\"dicas de tabela din\u00e2mica do Excel dicas para arquivo est\u00e1 conectado\"><\/figure><\/div><p> Agora voc\u00ea pode criar uma tabela din\u00e2mica com todas as op\u00e7\u00f5es de campo do arquivo de origem externo. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 4. O assistente cl\u00e1ssico de tabela din\u00e2mica e gr\u00e1fico din\u00e2mico <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Em vez de criar uma tabela din\u00e2mica na guia Inserir, voc\u00ea tamb\u00e9m pode usar o \u201cAssistente de tabela din\u00e2mica e gr\u00e1fico din\u00e2mico cl\u00e1ssico\u201d.<\/p><p> A \u00fanica coisa que gosto no assistente cl\u00e1ssico \u00e9 que existe uma op\u00e7\u00e3o para <a href=\"https:\/\/exceladvisor.org\/pt\/consolidar\/\" data-wpil=\"url\">extrair dados de v\u00e1rias planilhas<\/a> antes de criar uma tabela din\u00e2mica. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-lassistant-de-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para criar uma tabela din\u00e2mica usando o assistente de tabela din\u00e2mica\"><\/figure><\/div><p> Uma maneira f\u00e1cil de abrir este assistente \u00e9 usar o atalho de teclado: <strong><span style=\"color: #000000;\">Alt + D + P.<\/span><\/strong> <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-4-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 5. Campos de pesquisa <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-4-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Nas configura\u00e7\u00f5es dos campos da tabela din\u00e2mica, existe uma op\u00e7\u00e3o para pesquisar os campos. Voc\u00ea pode pesquisar o campo onde h\u00e1 centenas de colunas. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-ajouter-des-champs-via-la-barre-de-recherche-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar campos por meio da barra de pesquisa\"><\/figure><\/div><p> Quando voc\u00ea come\u00e7a a digitar na caixa de pesquisa, ela come\u00e7a a filtrar as colunas. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-5-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 6. Alterar o estilo da janela do campo da tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-5-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma op\u00e7\u00e3o que voc\u00ea pode usar para alterar o estilo da \u201cjanela de campo da tabela din\u00e2mica\u201d. Clique no \u00edcone de engrenagem no canto superior direito e selecione o estilo que deseja aplicar. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-changer-le-style-de-la-fenetre-de-champ-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica, dicas do Excel, truques para alterar o estilo da janela do campo\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-6-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 7. Classifique a ordem de sua lista de campos <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-6-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea tiver um grande conjunto de dados, poder\u00e1 classificar a lista de campos em ordem de A a Z para facilitar a localiza\u00e7\u00e3o dos campos obrigat\u00f3rios.<\/p><p> Clique no \u00edcone de engrenagem no canto superior direito e selecione \u201cClassificar de A a Z\u201d. Por padr\u00e3o, os campos s\u00e3o classificados pelos dados de origem. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-trier-la-liste-des-champs-1.png\" sizes=\"\" srcset=\"\" alt=\"Excel-tabela din\u00e2mica-conselhos-truques-para-classificar-lista de campos\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-7-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 8. Abrir\/Mostrar lista de campos <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-7-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Acontece comigo que quando crio uma tabela din\u00e2mica e clico nela, aparece a &#8220;Lista de Campos&#8221; do lado direito e isso acontece toda vez que clico em uma tabela din\u00e2mica.<\/p><p> Mas voc\u00ea pode desativ\u00e1-lo e para isso basta clicar no \u201cBot\u00e3o Feild List\u201d na aba \u201cPivotTable Analyze\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-masquer-afficher-le-volet-de-la-liste-des-champs.png\" sizes=\"auto, \" srcset=\"\" alt=\"Dicas da tabela din\u00e2mica do Excel, truques para ocultar o painel da lista de campos\" width=\"513\" height=\"212\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-8-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 9. Nomeie uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-8-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Depois de criar uma tabela din\u00e2mica, a pr\u00f3xima coisa que acho que voc\u00ea precisa fazer \u00e9 nomear uma tabela din\u00e2mica.<\/p><p> E para isso, voc\u00ea pode ir at\u00e9 a aba Analisar \u279c Tabela Din\u00e2mica \u279c Op\u00e7\u00f5es da Tabela Din\u00e2mica e inserir o novo nome. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-changer-le-nom-dun-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para alterar o nome de uma tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-9-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 10. Crie uma tabela din\u00e2mica na vers\u00e3o online do Excel <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-9-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Recentemente, a op\u00e7\u00e3o de criar uma tabela din\u00e2mica foi adicionada ao aplicativo online Excel (op\u00e7\u00f5es limitadas).<\/p><p> \u00c9 t\u00e3o simples quanto criar um piv\u00f4 na aplica\u00e7\u00e3o web do Excel:<\/p><p> Na guia Inserir, clique no bot\u00e3o \u201cTabela Din\u00e2mica\u201d no grupo de tabelas\u2026 <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-Creer-un-tableau-croise-dynamique-dans-lapplication-en-ligne-Excel-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas Crie uma tabela din\u00e2mica no aplicativo Excel Online\"><\/figure><\/div><p> \u2026em seguida, selecione o intervalo de dados de origem\u2026 <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-selectionner-les-donnees-pour-creer-un-tableau-croise-dynamique-dans-lapplication-en-ligne-Excel-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para selecionar dados para criar uma tabela din\u00e2mica no aplicativo Excel Online\"><\/figure><\/div><p> \u2026e a planilha onde deseja inseri-la\u2026<\/p><p> \u2026e, no final, clique em OK. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-10-761886e1-cbb0-43cd-af8a-7398268ed6e5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-761886e1-cbb0-43cd-af8a-7398268ed6e5\"> 11. C\u00f3digo VBA para criar uma tabela din\u00e2mica no Excel <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-10-761886e1-cbb0-43cd-af8a-7398268ed6e5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se quiser automatizar o processo de cria\u00e7\u00e3o de tabela din\u00e2mica, voc\u00ea pode usar o c\u00f3digo VBA para isso. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-utiliser-le-code-vba-1.gif\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel para usar c\u00f3digo VBA\"><\/figure><\/div><p> <a href=\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-1\/\" data-wpil=\"url\">Neste guia<\/a> , mencionei um processo passo a passo simples para criar uma tabela din\u00e2mica usando c\u00f3digo de macro.<\/p><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Formate uma tabela din\u00e2mica como um PRO<\/h2><p> Como voc\u00ea pode usar uma tabela din\u00e2mica como relat\u00f3rio, \u00e9 importante fazer algumas altera\u00e7\u00f5es na formata\u00e7\u00e3o padr\u00e3o. <\/p><div id=\"ub-content-toggle-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 1. Altere o estilo da tabela din\u00e2mica ou crie um novo estilo <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existem v\u00e1rios estilos predefinidos no Excel para uma tabela din\u00e2mica que voc\u00ea pode aplicar com apenas um clique.<\/p><p> Na aba projetada, voc\u00ea pode encontrar \u201cEstilo de tabela din\u00e2mica\u201d e ao clicar em \u201cMais\u201d, voc\u00ea pode simplesmente selecionar um estilo de sua prefer\u00eancia.<\/p><p> Voc\u00ea tamb\u00e9m pode criar um novo estilo personalizado, usando a op\u00e7\u00e3o \u201cNovo estilo de tabela din\u00e2mica\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-appliquer-du-style-a-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Truques para estilizar uma tabela din\u00e2mica\"><\/figure><\/div><p> Quando terminar seu estilo personalizado, voc\u00ea pode simplesmente salv\u00e1-lo para usar na pr\u00f3xima vez, ele ainda estar\u00e1 l\u00e1. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 2. Preservar a formata\u00e7\u00e3o das c\u00e9lulas ao atualizar uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> V\u00e1 para Op\u00e7\u00f5es de Tabela Din\u00e2mica (clique com o bot\u00e3o direito na Tabela Din\u00e2mica e v\u00e1 para Op\u00e7\u00f5es de Tabela Din\u00e2mica) e marque a caixa \u201cPreservar formata\u00e7\u00e3o de c\u00e9lula ao atualizar\u201d.<\/p><p> A vantagem desta op\u00e7\u00e3o \u00e9 que toda vez que voc\u00ea atualizar sua tabela din\u00e2mica, voc\u00ea n\u00e3o perder\u00e1 a formata\u00e7\u00e3o que possui. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-les-tableaux-croises-dynamiques-Excel-Astuces-pour-conserver-la-mise-en-forme-des-cellules-lorsque-vous-mettez-a-jour-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para manter a formata\u00e7\u00e3o de c\u00e9lulas ao atualizar uma tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 3. Desative a atualiza\u00e7\u00e3o autom\u00e1tica de largura ao atualizar uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Al\u00e9m de formatar um, voc\u00ea tamb\u00e9m precisa mant\u00ea-lo, que \u00e9 \u201cLargura da Coluna\u201d.<\/p><p> Para fazer isso, v\u00e1 em \u201cOp\u00e7\u00f5es da tabela din\u00e2mica\u201d e desmarque \u201cAjustar automaticamente a largura da coluna na atualiza\u00e7\u00e3o\u201d e clique em OK. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-desactiver-la-mise-a-jour-automatique-de-la-largeur-lorsque-vous-mettez-a-jour-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para desativar a atualiza\u00e7\u00e3o autom\u00e1tica de largura ao atualizar uma tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 4. Repita os r\u00f3tulos dos itens <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Ao usar v\u00e1rios itens em uma tabela din\u00e2mica, voc\u00ea pode simplesmente repetir os r\u00f3tulos dos itens principais. Facilita a compreens\u00e3o da estrutura da tabela din\u00e2mica.<\/p><ul><li> Selecione a tabela din\u00e2mica e navegue at\u00e9 a guia \u201cDesign\u201d.<\/li><li> Na guia Design, v\u00e1 para Layout \u279c Layout do relat\u00f3rio \u279c Repetir todos os r\u00f3tulos de item. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-repeter-toutes-les-etiquettes-darticles-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para repetir todos os r\u00f3tulos de itens\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-4-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 5. Formatando valores <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-4-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Na maioria dos casos, voc\u00ea deve formatar os valores ap\u00f3s criar uma tabela din\u00e2mica.<\/p><p> Por exemplo, se voc\u00ea deseja alterar o n\u00famero de casas decimais dos n\u00fameros. Basta selecionar a coluna de valores e abrir a op\u00e7\u00e3o \u201cFormatar c\u00e9lula\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-formater-les-valeurs.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para formatar valores\"><\/figure><\/div><p> E a partir desta op\u00e7\u00e3o voc\u00ea pode alterar os n\u00fameros decimais. Na op\u00e7\u00e3o \u201cFormato\u201d voc\u00ea pode at\u00e9 alterar outras op\u00e7\u00f5es. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-5-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 6. Altere o estilo da fonte das tabelas din\u00e2micas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-5-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Uma das minhas coisas favoritas sobre formata\u00e7\u00e3o \u00e9 alterar o \u201cestilo da fonte\u201d de uma tabela din\u00e2mica.<\/p><p> Voc\u00ea pode usar a op\u00e7\u00e3o de formato, mas a maneira mais f\u00e1cil \u00e9 fazer isso na guia P\u00e1gina inicial. Selecione toda a tabela din\u00e2mica e selecione o estilo da fonte. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-changer-le-style-de-police-des-tableaux-croises-dynamiques-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas da tabela din\u00e2mica do Excel Dicas para alterar o estilo da fonte da tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-6-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 7. Ocultar\/Mostrar subtotais <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-6-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Ao adicionar uma tabela din\u00e2mica com mais de um campo de item, voc\u00ea obt\u00e9m subtotais para o campo principal.<\/p><p> Mas \u00e0s vezes n\u00e3o h\u00e1 necessidade de exibir subtotais. Nessa situa\u00e7\u00e3o, voc\u00ea pode ocult\u00e1-los fazendo o seguinte:<\/p><ul><li> Clique na tabela din\u00e2mica e v\u00e1 para a guia Analisar.<\/li><li> Na guia Analisar, v\u00e1 para Layout \u279c Subtotais \u279c N\u00e3o mostrar subtotais. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-les-tableaux-croises-dynamiques-Excel-Astuces-pour-masquer-les-sous-totaux.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para ocultar subtotais\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-7-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 8. Ocultar\/mostrar total geral <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-7-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Assim como os subtotais, voc\u00ea tamb\u00e9m pode ocultar e mostrar os totais gerais. Abaixo est\u00e3o as etapas simples para fazer isso.<\/p><ul><li> Clique na tabela din\u00e2mica e v\u00e1 para a guia Analisar.<\/li><li> Na guia Analisar, v\u00e1 para Layout \u279c Total Geral \u279c Desativado para Linhas e Colunas. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-masquer-les-totaux-generaux-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para ocultar totais gerais\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-8-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 9. Formato de dois d\u00edgitos em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-8-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Em uma tabela din\u00e2mica normal, temos apenas um formato de valores na coluna de valores.<\/p><p> Por\u00e9m, existem algumas situa\u00e7\u00f5es (raras) em que voc\u00ea precisa ter formatos diferentes em uma \u00fanica tabela din\u00e2mica, como abaixo. Para fazer isso, voc\u00ea precisa <strong>usar uma formata\u00e7\u00e3o personalizada<\/strong> . <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-9-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 10. Aplique um tema \u00e0 tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-9-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> No Excel, existem temas de cores predefinidos que voc\u00ea pode usar. Esses temas tamb\u00e9m podem ser aplicados a tabelas din\u00e2micas. V\u00e1 para a guia \u201cLayout\u201d e clique no menu suspenso \u201cTemas\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-appliquer-le-theme-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para aplicar o tema\"><\/figure><\/div><p> Existem mais de 32 temas que voc\u00ea pode aplicar com apenas um clique ou pode salvar seu estilo de formata\u00e7\u00e3o atual como tema. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-10-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 11. Alterando o layout de uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-10-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Para cada tabela din\u00e2mica, voc\u00ea pode escolher um layout.<\/p><p> No Excel (se voc\u00ea estiver usando a vers\u00e3o 2007 ou superior) voc\u00ea pode ter tr\u00eas layouts diferentes. Na guia Design, v\u00e1 para Relat\u00f3rio de layout \u279c Layout e selecione o layout que deseja aplicar. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-Modification-de-la-disposition-dun-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para alterar o layout de uma tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-11-d1c55018-93c4-479e-a4a2-994e2ea23edc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-d1c55018-93c4-479e-a4a2-994e2ea23edc\"> 12. Colunas e linhas listradas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-11-d1c55018-93c4-479e-a4a2-994e2ea23edc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Uma das primeiras coisas que fa\u00e7o ao criar uma tabela din\u00e2mica \u00e9 aplicar &#8220;Linha e coluna com marca&#8221;.<\/p><p> Voc\u00ea pode aplic\u00e1-lo na aba de design e marcar \u201cColuna com faixas\u201d e \u201cLinhas com faixas\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-appliquer-des-colonnes-et-des-lignes-en-bandes-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para aplicar colunas e linhas com faixas\"><\/figure><\/div><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Filtrar dados em uma tabela din\u00e2mica<\/h2><p> O que torna a Tabela Din\u00e2mica uma das ferramentas de an\u00e1lise de dados mais poderosas s\u00e3o os \u201cFiltros\u201d. <\/p><div id=\"ub-content-toggle-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 1. Habilitar\/desabilitar filtros <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Assim como um filtro normal, voc\u00ea pode ativar\/desativar filtros em uma tabela din\u00e2mica. Na \u201cGuia Analisar\u201d, voc\u00ea pode clicar no bot\u00e3o \u201cCabe\u00e7alho de campo\u201d para ativar ou desativar filtros. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-desactiver-les-filtres-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para desativar filtros\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 2. Sele\u00e7\u00e3o atual para filtrar <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Voc\u00ea selecionou uma ou mais c\u00e9lulas em uma tabela din\u00e2mica e deseja filtrar apenas essas c\u00e9lulas. Aqui est\u00e1 a op\u00e7\u00e3o que voc\u00ea pode usar.<\/p><p> Ap\u00f3s selecionar as c\u00e9lulas, clique com o bot\u00e3o direito e v\u00e1 em \u201cFiltrar\u201d, depois selecione \u201cManter apenas os itens selecionados\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-la-selection-actuelle-au-filtre-1.png\" sizes=\"\" srcset=\"\" alt=\"truques de dicas do Excel da tabela din\u00e2mica para a sele\u00e7\u00e3o atual filtrar\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 3. Ocultar sele\u00e7\u00e3o <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Assim como filtrar c\u00e9lulas selecionadas, voc\u00ea tamb\u00e9m pode ocult\u00e1-las. Para fazer isso, v\u00e1 em \u201cFiltro\u201d e em seguida selecione \u201cOcultar itens selecionados\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-masquer-la-selection-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para ocultar a sele\u00e7\u00e3o\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 4. Filtro de valor e r\u00f3tulo <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Al\u00e9m dos filtros normais, voc\u00ea usa filtros de r\u00f3tulo e filtros de valor para filtrar com um valor ou crit\u00e9rio espec\u00edfico.<\/p><p> <strong>Filtro de r\u00f3tulo:<\/strong> <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-etiqueter-le-filtre-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para filtro de r\u00f3tulos\"><\/figure><\/div><p> <strong>Filtro de valor:<\/strong> <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-filtrer-les-valeurs-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para filtrar valores\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-4-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 5. Use r\u00f3tulo e filtro de valor juntos <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-4-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Como falei na dica acima, voc\u00ea pode ter o campo Label e Value, mas precisa habilitar uma op\u00e7\u00e3o para usar essas duas op\u00e7\u00f5es de filtro juntas.<\/p><ul><li> Primeiro, <span style=\"color: #000000;\">abra as \u201cOp\u00e7\u00f5es da Tabela Din\u00e2mica\u201d<\/span> e v\u00e1 para a aba \u201cTotal e Filtro\u201d.<\/li><li> <span style=\"color: #000000;\">Na aba \u201cTotal e filtro\u201d, marque a caixa \u201cPermitir m\u00faltiplos filtros por campo\u201d<\/span> .<\/li><li> Depois disso, clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-autoriser-plusieurs-filtres-par-champ-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para permitir v\u00e1rios filtros por campo\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-5-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 6. Filtre os primeiros 10 valores <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-5-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Uma das minhas op\u00e7\u00f5es favoritas em filtros \u00e9 filtrar <span style=\"color: #000000;\"><strong>por \u201cTop 10 Values\u201d<\/strong><\/span> . Esta op\u00e7\u00e3o de filtro \u00e9 \u00fatil ao criar um relat\u00f3rio instant\u00e2neo.<\/p><p> Para isso, voc\u00ea deve ir at\u00e9 o \u201cFiltro de Valores\u201d e clicar em \u201cTop 10\u201d e depois clicar em OK. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-filtrer-les-10-premieres-valeurs-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel para filtrar os 10 principais valores\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-6-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 7. Filtrar campos na janela Campos da tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-6-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se quiser filtrar ao criar uma tabela din\u00e2mica, voc\u00ea pode faz\u00ea-lo na janela \u201cCampo Din\u00e2mico\u201d.<\/p><p> Para filtrar os valores em uma coluna, voc\u00ea pode clicar na seta para baixo \u00e0 direita e filtrar os valores conforme necess\u00e1rio. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-filtrer-les-champs-de-la-fenetre-des-champs-pivotants-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para filtrar campos na janela de campos da tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-7-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 8. Adicione um fatiador <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-7-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Uma das melhores coisas que encontrei para filtrar dados em uma tabela din\u00e2mica \u00e9 usar um &#8220;Slicer&#8221;.<\/p><p> Para inserir um slicer, basta ir at\u00e9 \u201cAba Analisar\u201d e no grupo \u201cFiltro\u201d clicar no bot\u00e3o \u201cInserir Slicer\u201d, ap\u00f3s selecionar o campo para o qual deseja inserir um slicer e clicar em OK. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-un-slicer-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques com dicas de tabela din\u00e2mica do Excel para adicionar uma segmenta\u00e7\u00e3o de dados\"><\/figure><\/div><p> Relacionado: <a href=\"https:\/\/exceladvisor.org\/pt\/fatiador-de-excel\/\">Excel SLICER \u2013 Um guia completo sobre como filtrar dados com ele<\/a> <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-8-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 9. Formate um slicer e outras op\u00e7\u00f5es <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-8-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Depois de inserir um segmento, voc\u00ea poder\u00e1 alterar seu estilo e formato.<\/p><ul><li> Selecione o slicer e v\u00e1 para a guia Op\u00e7\u00f5es.<\/li><li> Em \u201cSlicer Styles\u201d, clique no menu suspenso e selecione o estilo que deseja aplicar. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-formater-un-slicer-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica dicas do Excel dicas para formatar um slicer\"><\/figure><\/div><p> Al\u00e9m dos estilos, voc\u00ea pode alterar a configura\u00e7\u00e3o na janela de configura\u00e7\u00f5es: clique no bot\u00e3o \u201cConfigura\u00e7\u00f5es do Slicer\u201d para abrir a janela de configura\u00e7\u00f5es. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-formater-un-segment-et-dautres-options-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para formatar uma segmenta\u00e7\u00e3o de dados e outras op\u00e7\u00f5es\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-9-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 10. Fatiador \u00fanico para todas as tabelas din\u00e2micas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-9-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> \u00c0s vezes, quando voc\u00ea tem v\u00e1rias tabelas din\u00e2micas, \u00e9 dif\u00edcil controlar todas elas. Mas se voc\u00ea <a href=\"https:\/\/exceladvisor.org\/pt\/vincular-o-slicer-a-varias-tabelas-dinamicas\/\">conectar um \u00fanico segmento a v\u00e1rias tabelas din\u00e2micas<\/a> , poder\u00e1 controlar todos os piv\u00f4s sem esfor\u00e7o.<\/p><ul><li> Primeiro, insira um fatiador.<\/li><li> E, em seguida, clique com o bot\u00e3o direito no slicer e selecione \u201cReport Connections\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-un-seul-segment-pour-toutes-les-connexions-de-rapport-de-tableaux-croises-dynamiques-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas de fatiador \u00fanico para todas as conex\u00f5es de relat\u00f3rio de tabela din\u00e2mica\"><\/figure><\/div><ul><li> Na caixa de di\u00e1logo, selecione todos os piv\u00f4s e clique em OK.<\/li><\/ul><div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-un-seul-trancheur-pour-tous-les-tableaux-croises-dynamiques-Selectionnez-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas de fatiador \u00fanico para todas as tabelas din\u00e2micas Selecionar\"><\/figure><\/div><p> Agora voc\u00ea pode simplesmente filtrar todas as tabelas din\u00e2micas com uma \u00fanica segmenta\u00e7\u00e3o de dados. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-10-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 11. Adicione uma linha do tempo <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-10-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Ao contr\u00e1rio de um segmento, uma linha do tempo \u00e9 uma ferramenta de filtragem espec\u00edfica para filtrar datas e \u00e9 muito mais poderosa que o filtro normal.<\/p><p> Para inserir um slicer, basta ir at\u00e9 \u201cAba Analisar\u201d e no grupo \u201cFiltro\u201d clicar no bot\u00e3o \u201c <a href=\"https:\/\/exceladvisor.org\/pt\/filtro-de-linha-do-tempo\/\">Inserir Linha do Tempo<\/a> \u201d e em seguida selecionar a coluna de data e clicar em OK. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-une-chronologie-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar uma linha do tempo\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-11-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 12. Formate um filtro de linha do tempo e outras op\u00e7\u00f5es <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-11-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Depois de inserir uma linha do tempo, voc\u00ea poder\u00e1 alterar seu estilo e formato.<\/p><ul><li> Selecione a linha do tempo e v\u00e1 para a guia Op\u00e7\u00f5es.<\/li><li> Em \u201cEstilos de linha do tempo\u201d, clique no menu suspenso e selecione o estilo que deseja aplicar. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-formater-un-filtre-de-chronologie-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para formatar um filtro de linha do tempo\"><\/figure><\/div><p> Al\u00e9m dos estilos, voc\u00ea tamb\u00e9m pode alterar as configura\u00e7\u00f5es. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-formater-un-filtre-de-chronologie-et-dautres-options.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para formatar um filtro de linha do tempo e outras op\u00e7\u00f5es\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-12-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 13. Filtrar usando curingas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-12-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Voc\u00ea pode usar <a href=\"https:\/\/exceladvisor.org\/pt\/curingas-2\/\" data-wpil=\"url\">curingas do Excel<\/a> em todas as op\u00e7\u00f5es de filtro onde for necess\u00e1rio inserir o valor a ser filtrado. Veja os exemplos abaixo onde usei um asterisco para filtrar valores come\u00e7ando com a letra A. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-les-caracteres-generiques-avec-des-filtres-1.gif\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas curinga com filtros\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-13-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-ae85802f-b8b7-4c4c-a931-4787b3a7003e\"> 14. Limpe todos os filtros <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-13-ae85802f-b8b7-4c4c-a931-4787b3a7003e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea aplicou filtros em v\u00e1rios campos, poder\u00e1 remover todos esses filtros na guia Analisar \u279c A\u00e7\u00f5es \u279c Limpar \u279c Limpar filtro. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-effacer-tous-les-filtres-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para limpar todos os filtros\"><\/figure><\/div><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Dicas para aproveitar ao m\u00e1ximo as tabelas din\u00e2micas<\/h2><p> Trabalhar com uma tabela din\u00e2mica pode ser mais f\u00e1cil se voc\u00ea conhecer as dicas que mencionei acima.<\/p><p> Essas dicas ajudar\u00e3o voc\u00ea a economizar mais de 2 horas por semana. <\/p><div id=\"ub-content-toggle-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 1. Atualize manualmente uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> As tabelas din\u00e2micas s\u00e3o din\u00e2micas, portanto, quando voc\u00ea adiciona novos dados ou atualiza valores nos dados de origem, \u00e9 necess\u00e1rio atualiz\u00e1-los para que a tabela din\u00e2mica obtenha todos os novos valores adicionados da origem. Atualizar uma tabela din\u00e2mica \u00e9 simples:<\/p><ul><li> Primeiro, clique com o bot\u00e3o direito em um piv\u00f4 e selecione \u201cAtualizar\u201d.<\/li><li> Em segundo lugar, v\u00e1 para a guia \u201cAnalisar\u201d e clique no bot\u00e3o \u201cAtualizar\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-actualiser-manuellement-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para atualizar manualmente uma tabela din\u00e2mica\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 2. Atualize uma tabela din\u00e2mica ao abrir um arquivo <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma op\u00e7\u00e3o simples no Excel que voc\u00ea pode ativar e fazer com que uma tabela din\u00e2mica seja atualizada automaticamente sempre que abrir a pasta de trabalho. Para fazer isso, aqui est\u00e3o as etapas simples:<\/p><ul><li> Primeiro, clique com o bot\u00e3o direito em uma tabela din\u00e2mica e v\u00e1 para \u201cOp\u00e7\u00f5es de tabela din\u00e2mica\u201d.<\/li><li> Depois disso, v\u00e1 at\u00e9 a aba \u201cDados\u201d e marque a caixa \u201cAtualizar dados ao abrir arquivo\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-cocher-Actualiser-le-tableau-croise-dynamique-lors-de-louverture-dun-fichier-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Truques para marcar a caixa Atualizar tabela din\u00e2mica ao abrir um arquivo\"><\/figure><\/div><ul><li> No final, clique em OK.<\/li><\/ul><p> Agora, toda vez que voc\u00ea abrir a pasta de trabalho, esta tabela din\u00e2mica ser\u00e1 atualizada instantaneamente. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 3. Atualize os dados ap\u00f3s um intervalo de tempo espec\u00edfico <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea deseja atualizar sua tabela din\u00e2mica automaticamente ap\u00f3s um intervalo espec\u00edfico, esta dica \u00e9 para voc\u00ea.<\/p><p> \u2026 Veja como fazer isso.<\/p><ul><li> Primeiramente, ao criar uma Tabela Din\u00e2mica, na janela \u201cCriar Tabela Din\u00e2mica\u201d, marque a caixa \u201cAdicionar estes dados ao modelo de dados\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-ces-donnees-au-modele-de-donnees-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel para adicionar esses dados ao modelo de dados\"><\/figure><\/div><ul><li> Depois disso, depois de criar uma tabela din\u00e2mica, selecione uma das c\u00e9lulas e v\u00e1 para \u201cAba Analisar\u201d.<\/li><li> Na guia Analisar, Dados \u279c Editar fonte de dados \u279c Propriedades da conex\u00e3o. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-cliquer-sur-les-proprietes-de-connexion-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para clicar em propriedades de conex\u00e3o\"><\/figure><\/div><ul><li> Agora, em \u201cPropriedades da conex\u00e3o\u201d, na aba de uso, marque a caixa \u201cAtualizar a cada\u201d e insira os minutos. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-du-temps-pour-referencer-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar tempo para atualizar uma tabela din\u00e2mica\"><\/figure><\/div><ul><li> No final, clique em OK.<\/li><\/ul><p> Agora, ap\u00f3s esse per\u00edodo espec\u00edfico inserido, seu piv\u00f4 ser\u00e1 atualizado automaticamente. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 4. Substitua os valores de erro <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> \u00c0s vezes, quando voc\u00ea tem erros nos dados de origem, eles refletem o mesmo no piv\u00f4 e isso n\u00e3o \u00e9 nada bom.<\/p><p> A melhor maneira \u00e9 substituir esses erros por um valor significativo.<\/p><p> Abaixo est\u00e3o as etapas a seguir:<\/p><ul><li> Primeiro, clique com o bot\u00e3o direito em sua tabela din\u00e2mica e abra Op\u00e7\u00f5es de tabela din\u00e2mica.<\/li><li> Agora, em \u201cLayout e Formato\u201d, marque a caixa \u201cPara mostrar valor de erro\u201d e insira o valor na caixa de entrada. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-entrer-la-valeur-des-cellules-derreur-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para inserir erro de valor de c\u00e9lula\"><\/figure><\/div><ul><li> No final, clique em OK.<\/li><\/ul><p> Agora, para todos os erros, voc\u00ea ter\u00e1 o valor especificado. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-4-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 5. Substitua as c\u00e9lulas vazias <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-4-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Digamos que voc\u00ea tenha um piv\u00f4 para dados de vendas e algumas c\u00e9lulas estejam em branco.<\/p><p> Porque uma pessoa que n\u00e3o sabe por que essas c\u00e9lulas est\u00e3o vazias pode perguntar sobre isso. Portanto, \u00e9 melhor substitu\u00ed-lo por uma palavra significativa.<\/p><p> \u2026etapas simples que voc\u00ea precisa seguir para isso.<\/p><ul><li> Primeiro, \u201cclique com o bot\u00e3o direito\u201d em sua tabela din\u00e2mica e abra as op\u00e7\u00f5es da tabela din\u00e2mica.<\/li><li> Agora, em \u201cLayout e Formato\u201d, marque a caixa \u201cPara mostrar c\u00e9lulas vazias\u201d e insira o valor na caixa de entrada. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/9-3.png\" sizes=\"\" srcset=\"\" alt=\"truques de tabela din\u00e2mica insira valor para c\u00e9lulas vazias\"><\/figure><\/div><ul><li> No final, clique em OK.<\/li><\/ul><p> Agora, para todas as c\u00e9lulas vazias, voc\u00ea ter\u00e1 o valor especificado. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-5-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 6. Defina um formato num\u00e9rico <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-5-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Digamos que voc\u00ea tenha um piv\u00f4 para dados de vendas e algumas c\u00e9lulas estejam vazias.<\/p><p> Porque uma pessoa que n\u00e3o sabe por que essas c\u00e9lulas est\u00e3o vazias pode perguntar sobre isso. Portanto, \u00e9 melhor substitu\u00ed-lo por uma palavra significativa.<\/p><p> \u2026etapas simples que voc\u00ea precisa seguir para isso.<\/p><ul><li> Primeiro, \u201cclique com o bot\u00e3o direito\u201d em sua tabela din\u00e2mica e abra as op\u00e7\u00f5es da tabela din\u00e2mica.<\/li><li> Agora, em \u201cLayout e Formato\u201d, marque a caixa \u201cPara mostrar c\u00e9lulas vazias\u201d e insira o valor na caixa de entrada. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/9-3.png\" sizes=\"\" srcset=\"\" alt=\"truques de tabela din\u00e2mica insira valor para c\u00e9lulas vazias\"><\/figure><\/div><ul><li> No final, clique em OK.<\/li><\/ul><p> Agora, para todas as c\u00e9lulas vazias, voc\u00ea ter\u00e1 o valor especificado. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-6-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 7. Adicione uma linha em branco ap\u00f3s cada elemento <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-6-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Agora suponha que voc\u00ea tenha uma grande tabela din\u00e2mica com v\u00e1rios itens.<\/p><p> Aqui voc\u00ea pode inserir uma linha em branco ap\u00f3s cada elemento para que n\u00e3o haja confus\u00e3o no piv\u00f4. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-une-ligne-vide-apres-chaque-element-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar uma linha em branco ap\u00f3s cada item\"><\/figure><\/div><p> Confira estas etapas a seguir:<\/p><ul><li> Selecione a tabela din\u00e2mica e v\u00e1 para a guia Design.<\/li><li> Na guia Design, v\u00e1 para Layout \u279c Linhas em branco \u279c Inserir linha em branco ap\u00f3s cada elemento. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-ajouter-une-ligne-vide-apres-chaque-element-de-longlet-Conception-Selectionnez-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar uma linha em branco ap\u00f3s cada item na sele\u00e7\u00e3o da guia Design\"><\/figure><\/div><p> A melhor coisa sobre essa op\u00e7\u00e3o \u00e9 que ela oferece uma vis\u00e3o mais clara do seu relat\u00f3rio. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-7-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 8. Arraste e solte itens em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-7-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea tem uma longa lista de itens em seu piv\u00f4, pode organizar todos esses itens em uma ordem personalizada simplesmente arrastando e soltando. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-astuces-de-tableau-croise-dynamique-pour-faire-glisser-et-deposer-des-elements-1.gif\" sizes=\"\" srcset=\"\" alt=\"Truques da tabela din\u00e2mica do Excel para arrastar e soltar itens\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-8-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 9. Crie v\u00e1rias tabelas din\u00e2micas a partir de uma <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-8-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Digamos que voc\u00ea criou uma tabela din\u00e2mica a partir de dados de vendas mensais e usou produtos como filtro de relat\u00f3rio.<\/p><p> Com a op\u00e7\u00e3o \u201cMostrar p\u00e1ginas de filtro de relat\u00f3rio\u201d, voc\u00ea pode criar v\u00e1rias planilhas com uma tabela din\u00e2mica para cada produto.<\/p><p> Digamos que se voc\u00ea tiver 10 produtos em um filtro din\u00e2mico, poder\u00e1 criar 10 planilhas diferentes com apenas um clique.<\/p><p> Siga esses passos:<\/p><ul><li> Selecione seu piv\u00f4 e v\u00e1 para a aba de an\u00e1lise.<\/li><li> Na guia Analisar, navegue at\u00e9 Tabela Din\u00e2mica \u279c Op\u00e7\u00f5es \u279c Mostrar p\u00e1ginas de filtro de relat\u00f3rio. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-creer-une-feuille-de-calcul-separee-pour-chaque-element-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para criar uma planilha separada para cada item\"><\/figure><\/div><p> Agora voc\u00ea tem quatro tabelas din\u00e2micas em quatro planilhas separadas. <\/p><figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-creer-une-feuille-de-calcul-separee-pour-chaque-option-delement.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para criar uma planilha separada para cada op\u00e7\u00e3o de item\"><\/figure><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-9-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 10. Op\u00e7\u00e3o de c\u00e1lculo de valor <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-9-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea adiciona uma coluna de valor no campo de valor, ela mostra SUM ou COUNT (\u00e0s vezes), mas h\u00e1 algumas outras coisas que voc\u00ea pode calcular aqui:<\/p><p> Para abrir as op\u00e7\u00f5es \u201cConfigura\u00e7\u00f5es de valor\u201d, selecione uma c\u00e9lula na coluna de valor e clique com o bot\u00e3o direito. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/conseils-sur-le-tableau-croise-dynamique-excel-astuces-pour-modifier-les-parametres-de-valeurs-pour-le-champ-de-valeur-1.png\" sizes=\"\" srcset=\"\" alt=\"dicas de tabela din\u00e2mica do Excel dicas para alterar as configura\u00e7\u00f5es de valores para o campo de valor\"><\/figure><\/div><p> E no menu de contexto, abra \u201cConfigura\u00e7\u00f5es do campo de valor\u201d e clique em<\/p><p> No campo \u201cResumir valor por\u201d, selecione o tipo de c\u00e1lculo que deseja exibir no piv\u00f4. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-10-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 11. Executando a coluna Total em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-10-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Digamos que voc\u00ea tenha uma venda de tabela din\u00e2mica por m\u00eas.<\/p><p> Agora voc\u00ea deseja inserir um total acumulado em sua tabela din\u00e2mica para mostrar o crescimento total das vendas durante todo o m\u00eas.<\/p><p> Aqui est\u00e3o as etapas:<\/p><ul><li> Clique com o bot\u00e3o direito nele e clique em \u201cConfigura\u00e7\u00e3o do campo de valor\u201d.<\/li><li> Na lista suspensa \u201cMostrar valores como\u201d, selecione \u201cTotal acumulado em\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-le-parametre-de-champ-de-valeur-totale-en-cours-dexecution-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar par\u00e2metros de campo de valor total em execu\u00e7\u00e3o\"><\/figure><\/div><ul><li> No final, clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-ajouter-une-colonne-de-total-cumule-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para adicionar uma coluna de total em execu\u00e7\u00e3o\"><\/figure><\/div><p> <a href=\"https:\/\/exceladvisor.org\/pt\/total-cumulativo\/\">Saiba mais sobre como adicionar um total acumulado a uma tabela din\u00e2mica<\/a> . <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-11-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 12. Adicionar linhas em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-11-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> A classifica\u00e7\u00e3o oferece uma maneira melhor de comparar as coisas entre si\u2026<\/p><p> \u2026e para inserir uma coluna de classifica\u00e7\u00e3o em uma tabela din\u00e2mica, voc\u00ea pode seguir os seguintes passos:<\/p><ul><li> Primeiro, insira o mesmo campo de dados duas vezes no piv\u00f4.<\/li><li> Depois disso, para o segundo campo, clique com o bot\u00e3o direito sobre ele e abra \u201cConfigura\u00e7\u00f5es do campo de valor\u201d.<\/li><li> V\u00e1 para a guia \u201cMostrar valores como\u201d e selecione \u201cOrdenar do maior para o menor\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-des-options-de-rangs-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar op\u00e7\u00f5es de linha\"><\/figure><\/div><ul><li> No final, clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-ajouter-une-colonne-de-classement-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para adicionar uma coluna de classifica\u00e7\u00e3o\"><\/figure><\/div><p> <a href=\"https:\/\/exceladvisor.org\/pt\/coluna-de-classificacoes\/\">\u2026clique aqui para saber mais sobre classifica\u00e7\u00e3o em uma tabela din\u00e2mica<\/a> . <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-12-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 13. Crie uma participa\u00e7\u00e3o percentual <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-12-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Imagine que voc\u00ea tem uma tabela din\u00e2mica para vendas de produtos.<\/p><p> E agora voc\u00ea deseja calcular a participa\u00e7\u00e3o percentual de todos os produtos nas vendas totais.<\/p><p> Passos para usar:<\/p><ul><li> Primeiro, insira o mesmo campo de dados duas vezes no piv\u00f4.<\/li><li> Depois disso, para o segundo campo, clique com o bot\u00e3o direito sobre ele e abra \u201cConfigura\u00e7\u00f5es do campo de valor\u201d.<\/li><li> V\u00e1 para a guia \u201cMostrar valores como\u201d e selecione \u201c% do total geral\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-creer-un-pourcentage-doptions-de-partage-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para criar op\u00e7\u00f5es de compartilhamento de porcentagem\"><\/figure><\/div><ul><li> No final, clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-creer-une-part-en-pourcentage-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para criar uma parcela percentual\"><\/figure><\/div><p> Tamb\u00e9m \u00e9 uma op\u00e7\u00e3o perfeita para criar um relat\u00f3rio r\u00e1pido. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-13-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 14. Mova uma tabela din\u00e2mica para uma nova planilha <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-13-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea cria uma Tabela Din\u00e2mica, o Excel solicita que voc\u00ea adicione uma nova planilha para a Tabela Din\u00e2mica\u2026<\/p><p> &#8230;mas tamb\u00e9m tem a op\u00e7\u00e3o de mover uma tabela din\u00e2mica existente para uma nova planilha.<\/p><ul><li> Para fazer isso, v\u00e1 em \u201cAba Analisar\u201d \u279c A\u00e7\u00f5es \u279c Mover tabelas din\u00e2micas. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-deplacer-un-tableau-croise-dynamique-vers-une-nouvelle-feuille-de-calcul-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para mover uma tabela din\u00e2mica para uma nova planilha\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-14-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 15. Desative GetPivotData <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-14-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma situa\u00e7\u00e3o em que voc\u00ea precisa fazer refer\u00eancia a uma c\u00e9lula em um piv\u00f4.<\/p><p> Por\u00e9m, pode haver um problema porque quando voc\u00ea se refere a uma c\u00e9lula em um piv\u00f4, o Excel usa automaticamente a fun\u00e7\u00e3o GetPivotData para refer\u00eancia.<\/p><p> O melhor \u00e9 que voc\u00ea pode desativ\u00e1-lo e aqui est\u00e3o os passos:<\/p><ul><li> V\u00e1 para a guia Arquivo \u279c Op\u00e7\u00f5es.<\/li><li> Nas op\u00e7\u00f5es, v\u00e1 em F\u00f3rmulas \u279c Trabalhar com f\u00f3rmulas \u279c desmarque \u201cUsar fun\u00e7\u00f5es GetPivotData para refer\u00eancia de tabela din\u00e2mica\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-desactiver-lobtention-de-donnees-pivot-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para desativar a obten\u00e7\u00e3o de dados din\u00e2micos\"><\/figure><\/div><p> Voc\u00ea tamb\u00e9m pode usar o c\u00f3digo VBA para isso:<\/p><p> SubdisableGetPivotData()<\/p><p> Application.GenerateGetPivotData = Falso<\/p><p> Finalizando a legenda<\/p><p> <strong><span style=\"color: #ea493f;\">Confira estes \u279c<\/span> Os 100 principais c\u00f3digos VBA do Excel + arquivo PDF<\/strong> <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-15-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 16. Agrupar datas em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-15-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Imagine que voc\u00ea deseja criar uma tabela din\u00e2mica por m\u00eas, mas tem datas em seus dados.<\/p><p> Nesta situa\u00e7\u00e3o, voc\u00ea ter\u00e1 que adicionar uma coluna extra por meses.<\/p><p> Mas a melhor maneira \u00e9 criar usando m\u00e9todos de agrupamento de datas na tabela din\u00e2mica. Usando este m\u00e9todo, voc\u00ea n\u00e3o precisa adicionar uma coluna auxiliar.<\/p><p> Use as etapas abaixo:<\/p><ul><li> Primeiro, voc\u00ea precisa inserir a data como um item de linha em sua tabela din\u00e2mica. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-regrouper-les-dates-ajouter-une-colonne-de-date-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel para agrupar datas e adicionar uma coluna de data\"><\/figure><\/div><ul><li> Clique com o bot\u00e3o direito na tabela din\u00e2mica e selecione \u201cGrupo\u2026\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-grouper-les-dates-cliquez-sur-le-groupe-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica dicas do excel truques para agrupar datas clique no grupo\"><\/figure><\/div><ul><li> Selecione \u201cM\u00eas\u201d na se\u00e7\u00e3o por e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-regrouper-les-dates-selectionner-le-mois-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel para agrupar datas e selecionar m\u00eas\"><\/figure><\/div><p> Ir\u00e1 agrupar todas as datas em meses e se quiser saber mais sobre esta op\u00e7\u00e3o aqui est\u00e1 o guia completo. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-16-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 17. Agrupe dados num\u00e9ricos em uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-16-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Assim como as datas, voc\u00ea tamb\u00e9m pode agrupar valores num\u00e9ricos.<\/p><p> Os passos s\u00e3o simples.<\/p><ul><li> Clique com o bot\u00e3o direito na tabela din\u00e2mica e selecione \u201cGrupo\u2026\u201d.<\/li><li> Insira o valor para criar um intervalo de grupo na caixa \u201cpor\u201d e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-grouper-des-donnees-numeriques-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica, dicas do Excel, truques para agrupar dados num\u00e9ricos\"><\/figure><\/div><p> \u2026 clique aqui para saber como a op\u00e7\u00e3o de agrupamento de tabelas din\u00e2micas pode ajud\u00e1-lo a criar um histograma no Excel. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-17-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 18. <strong>Colunas de grupo<\/strong> <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-17-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Para agrupar colunas como linhas, voc\u00ea pode seguir as mesmas etapas das linhas. Mas voc\u00ea precisa selecionar um cabe\u00e7alho de coluna antes disso. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-18-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 19. Desagrupar linhas e colunas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-18-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea n\u00e3o precisa de grupos em sua tabela din\u00e2mica, voc\u00ea pode simplesmente desagrupar eles clicando com o bot\u00e3o direito e selecionando \u201cDesagrupar\u201d. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-19-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 20. <strong>Use c\u00e1lculo em uma tabela din\u00e2mica<\/strong> <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-19-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Para se tornar um usu\u00e1rio avan\u00e7ado de tabela din\u00e2mica, voc\u00ea precisa aprender como criar um campo calculado e um item em uma tabela din\u00e2mica.<\/p><p> Digamos que na tabela din\u00e2mica abaixo voc\u00ea precise criar novos dados por campo multiplicando o campo de dados atual por 10. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-inserer-un-champ-personnalise-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para inserir um campo personalizado\"><\/figure><\/div><p> Nessa situa\u00e7\u00e3o, em vez de criar uma coluna separada em uma tabela din\u00e2mica, voc\u00ea pode inserir um item calculado.<\/p><p> \u279c <a href=\"https:\/\/exceladvisor.org\/pt\/calculo-em-tabela-dinamica\/\">um guia completo para criar um item e campo calculado em uma tabela din\u00e2mica<\/a> <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-20-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 21. Lista de f\u00f3rmulas utilizadas <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-20-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Depois de adicionar um c\u00e1lculo a uma tabela din\u00e2mica ou ter uma tabela din\u00e2mica com um campo ou item calculado, voc\u00ea poder\u00e1 ver a lista de f\u00f3rmulas usadas.<\/p><p> Para isso, basta acessar \u201cAba Analisar\u201d \u279c C\u00e1lculo \u279c Campos, Elementos e Conjuntos \u279c Listar F\u00f3rmulas. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-obtenir-la-liste-des-formules-utilisees-dans-lelement-du-tableau-croise-dynamique.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para obter a lista de f\u00f3rmulas usadas no item da tabela din\u00e2mica\"><\/figure><\/div><p> Voc\u00ea receber\u00e1 instantaneamente uma nova planilha com uma lista de f\u00f3rmulas usadas na tabela din\u00e2mica. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-21-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 22. Obtenha uma lista de valores exclusivos <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-21-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea tiver valores duplicados em sua data, poder\u00e1 usar uma tabela din\u00e2mica para obter uma lista de valores exclusivos.<\/p><ul><li> Primeiro, voc\u00ea precisa inserir uma tabela din\u00e2mica e, em seguida, adicionar a coluna onde h\u00e1 valores duplicados como um campo de linha.<\/li><li> Depois disso, copie este campo de linha do piv\u00f4 e cole-o como valores.<\/li><li> Agora, a lista que voc\u00ea tem como valores \u00e9 uma lista de valores exclusivos.<\/li><\/ul><p> O que eu gosto em usar uma tabela din\u00e2mica para verificar valores exclusivos \u00e9 que ela \u00e9 uma configura\u00e7\u00e3o que serve para todos.<\/p><p> Voc\u00ea n\u00e3o precisa cri\u00e1-lo repetidamente. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-22-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 23. Mostrar itens sem dados <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-22-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Digamos que voc\u00ea tenha entradas em seus dados de origem onde n\u00e3o h\u00e1 valores ou valores zero.<\/p><p> Voc\u00ea pode ativar a op\u00e7\u00e3o \u201cMostrar elementos sem dados\u201d no campo.<\/p><ul><li> Primeiro, clique com o bot\u00e3o direito no campo e abra \u201cConfigura\u00e7\u00f5es de campo\u201d.<\/li><li> Agora v\u00e1 em \u201cLayout e Impress\u00e3o\u201d e marque \u201cMostrar itens sem dados\u201d e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-afficher-les-elements-sans-donnees-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para mostrar itens sem dados\"><\/figure><\/div><p> Estrondo! Todos os itens para os quais voc\u00ea n\u00e3o possui dados ser\u00e3o exibidos na tabela din\u00e2mica. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-23-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 24. Diferen\u00e7a do valor anterior <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-23-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Esta \u00e9 uma das minhas op\u00e7\u00f5es favoritas de tabela din\u00e2mica.<\/p><p> Com isso voc\u00ea pode criar uma coluna onde mostra a diferen\u00e7a dos valores atuais em rela\u00e7\u00e3o ao valor anterior.<\/p><p> Digamos que voc\u00ea tenha um piv\u00f4 com valores de m\u00eas,&#8230;<\/p><p> \u2026ent\u00e3o, com esta op\u00e7\u00e3o\u2026<\/p><p> \u2026 voc\u00ea pode adicionar uma coluna de valor de diferen\u00e7a do m\u00eas anterior, como abaixo.<\/p><p> Aqui est\u00e3o as etapas:<\/p><ul><li> Primeiro, voc\u00ea precisa adicionar a coluna onde est\u00e3o os valores, duas vezes no campo de valor. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-inserer-la-colonne-de-difference-ajouter-deux-fois-la-colonne-de-valeur-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica dicas do Excel truques para inserir coluna de diferen\u00e7a adicionar coluna de valor duas vezes\"><\/figure><\/div><ul><li> Depois disso, para o segundo campo, abra \u201cConfigura\u00e7\u00e3o de valor\u201d e \u201cMostrar valor como\u201d.<\/li><li> Agora, na lista suspensa \u201cMostrar valores como\u201d, selecione \u201cDiferen\u00e7a de\u201d e selecione \u201cM\u00eas\u201d e \u201c(Anterior)\u201d em \u201cItem base\u201d.<\/li><li> No final, clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-inserer-la-colonne-de-difference-selectionner-precedent-parmi-les-options-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel para inserir coluna de diferen\u00e7a, selecione as op\u00e7\u00f5es anteriores\"><\/figure><\/div><p> Isso converter\u00e1 instantaneamente a coluna de valores em uma coluna diferente da anterior. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-inserer-une-colonne-de-difference-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para inserir uma coluna de diferen\u00e7a\"><\/figure><\/div>\n<\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-24-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 25. Desative Mostrar detalhes <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-24-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea clica duas vezes em uma c\u00e9lula de valor em uma tabela din\u00e2mica, os dados subjacentes a esse valor s\u00e3o exibidos. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-desactiver-afficher-les-details-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas da tabela din\u00e2mica do Excel Dicas para desativar a exibi\u00e7\u00e3o de detalhes\"><\/figure><\/div><p> Isso \u00e9 bom, mas n\u00e3o \u00e9 todo o tempo que voc\u00ea precisa para que isso aconte\u00e7a e \u00e9 por isso que voc\u00ea pode deslig\u00e1-lo se necess\u00e1rio.<\/p><p> Tudo o que voc\u00ea precisa fazer \u00e9 abrir as op\u00e7\u00f5es da tabela din\u00e2mica, ir at\u00e9 a \u201cGuia Dados\u201d e desmarcar \u201cAtivar detalhes de exibi\u00e7\u00e3o\u201d.<\/p><p> E ent\u00e3o clique em OK. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-25-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 26. Tabela din\u00e2mica para PowerPoint <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-25-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Aqui est\u00e3o as etapas simples para colar uma tabela din\u00e2mica em um slide do PowerPoint.<\/p><ul><li> Primeiro, selecione uma tabela din\u00e2mica e copie-a.<\/li><li> Depois disso, v\u00e1 at\u00e9 o slide do PowerPoint e abra as op\u00e7\u00f5es especiais de colagem. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-faire-pivoter-le-tableau-vers-Powerpoint-Paste-Special-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para girar a tabela no Powerpoint Colar especial\"><\/figure><\/div><ul><li> Agora, na caixa de di\u00e1logo de colagem especial, selecione \u201cObjeto gr\u00e1fico do Microsoft Excel\u201d e clique em OK.<\/li><\/ul><p> Insira uma imagem<\/p><p> Para fazer altera\u00e7\u00f5es na tabela din\u00e2mica, voc\u00ea deve clicar duas vezes no gr\u00e1fico. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-26-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 27. Adicionar tabela din\u00e2mica ao documento do Word <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-26-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Para adicionar uma tabela din\u00e2mica no Microsoft Word, voc\u00ea deve seguir os mesmos passos do PowerPoint. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-27-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 28. Expanda ou recolha os cabe\u00e7alhos dos campos <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-27-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea tiver v\u00e1rios campos de dimens\u00e3o em uma linha ou coluna, poder\u00e1 expandir ou recolher os campos externos.<\/p><p> Voc\u00ea precisa clicar no bot\u00e3o + para expandir e no bot\u00e3o \u2013 para recolher\u2026 <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-developper-ou-reduire-les-en-tetes-de-champ-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para expandir ou recolher cabe\u00e7alhos de campo\"><\/figure><\/div><p> &#8230;e para expandir ou recolher todos os grupos de uma vez, voc\u00ea pode clicar com o bot\u00e3o direito e escolher a op\u00e7\u00e3o. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-28-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 29. Ocultar e mostrar bot\u00f5es de expans\u00e3o ou recolhimento <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-28-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea tiver v\u00e1rios campos de dimens\u00e3o em uma linha ou coluna, poder\u00e1 expandir ou recolher os campos externos. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-masquer-les-boutons-de-developpement-ou-de-reduction-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Truques para ocultar bot\u00f5es de expans\u00e3o ou recolhimento\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-29-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 30. Conte apenas n\u00fameros em valores <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-29-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existe uma op\u00e7\u00e3o em uma tabela din\u00e2mica onde voc\u00ea pode contar o n\u00famero de c\u00e9lulas com o valor num\u00e9rico. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-utiliser-le-tableau-croise-dynamique-dans-une-feuille-de-calcul-protegee-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para usar a tabela din\u00e2mica em uma planilha protegida\"><\/figure><\/div><p> Para isso, basta abrir a \u201cOp\u00e7\u00e3o de Valor\u201d e selecionar \u201cN\u00famero de Contagem\u201d no \u201cCampo de Valor Resumido por\u201d e clicar em OK. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-30-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 31. Classifique os itens por valor correspondente <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-30-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Sim, voc\u00ea pode classificar por valores correspondentes.<\/p><ul><li> Basta abrir o filtro e selecionar \u201cMais op\u00e7\u00f5es de classifica\u00e7\u00e3o\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-trier-les-elements-en-fonction-dune-valeur-correspondante-ouvrir-le-filtre-1.png\" sizes=\"\" srcset=\"\" alt=\"excel-dicas-de-tabela-din\u00e2mica-truques-para-classificar-elementos-por-um-valor-correspondente-abrir-filtro\"><\/figure><\/div><ul><li> Em seguida, selecione \u201cAcesso (A a Z) por:\u201d e selecione a coluna para classificar e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-trier-les-elements-en-fonction-dune-valeur-correspondante-ouvrir-selectionner-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica, dicas do Excel, truques para classificar itens com base em um valor correspondente, abrir sele\u00e7\u00e3o\"><\/figure><\/div><p> <strong>Observa\u00e7\u00e3o:<\/strong><\/p><p> Se voc\u00ea tiver v\u00e1rias colunas de valores, poder\u00e1 usar apenas uma coluna para ordem de classifica\u00e7\u00e3o. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-31-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 32. Ordem de classifica\u00e7\u00e3o personalizada <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-31-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Sim, voc\u00ea pode usar uma ordem de classifica\u00e7\u00e3o personalizada para sua tabela din\u00e2mica.<\/p><ul><li> Para isso, ao abrir \u201cMais op\u00e7\u00f5es de classifica\u00e7\u00e3o\u201d, clique em \u201cMais op\u00e7\u00f5es\u201d e desmarque a caixa \u201cClassificar automaticamente quando o relat\u00f3rio for atualizado\u201d.<\/li><li> Depois disso, selecione a ordem de classifica\u00e7\u00e3o e clique em OK no final.<\/li><\/ul><p> Voc\u00ea precisa criar uma nova ordem de classifica\u00e7\u00e3o personalizada e, em seguida, cri\u00e1-la na guia Arquivo \u279c Op\u00e7\u00f5es \u279c Avan\u00e7ado \u279c Geral \u279c Editar lista personalizada. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-32-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 33. Layout diferido <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-32-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea ativar \u201cAtualiza\u00e7\u00e3o atrasada de layout\u201d e depois arrastar e soltar campos entre as \u00e1reas. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-la-mise-en-page-differee-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas de layout pregui\u00e7oso\"><\/figure><\/div><p> Sua tabela din\u00e2mica n\u00e3o ser\u00e1 atualizada a menos que voc\u00ea clique no bot\u00e3o Atualizar abaixo, no canto dos campos da tabela din\u00e2mica.<\/p><p> Isso torna mais f\u00e1cil para voc\u00ea verificar a tabela din\u00e2mica. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-33-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 34. Alterar nome do campo <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-33-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea insere um campo de valor, o nome obtido para o campo se parece com &#8220;Soma do Valor&#8221; ou &#8220;Contagem de Unidades&#8221;.<\/p><p> Mas \u00e0s vezes (bem, o tempo todo) voc\u00ea precisa alterar esse nome para um nome sem &#8220;Soma de&#8221; ou &#8220;Contagem de&#8221;.<\/p><p> Para fazer isso, basta remover \u201cContagem de\u201d ou \u201cSoma de\u201d da c\u00e9lula e adicionar um espa\u00e7o no final do nome.<\/p><p> Sim \u00e9 isso. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-34-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 35. Selecione toda a tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-34-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea quiser selecionar uma tabela din\u00e2mica inteira de uma vez:<\/p><p> Selecione uma das c\u00e9lulas da tabela din\u00e2mica e use o atalho de teclado Control + A.<\/p><p> Ou\u2026<\/p><p> V\u00e1 para a guia Analisar \u279c Selecione \u279c Tabela din\u00e2mica inteira. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-selectionner-lensemble-du-tableau-croise-dynamique-a-la-fois-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para selecionar a tabela din\u00e2mica inteira de uma vez\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-35-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 36. Converter em valores <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-35-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea deseja converter uma tabela din\u00e2mica em valores, basta selecionar a tabela din\u00e2mica inteira e ent\u00e3o:<\/p><p> Use Control + C para copi\u00e1-lo e cole especial \u279c Valores. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-36-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 37. Use uma tabela din\u00e2mica em uma planilha protegida <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-36-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Ao proteger uma planilha que cont\u00e9m uma tabela din\u00e2mica, certifique-se de verificar:<\/p><p> <strong>\u201cUsar a tabela din\u00e2mica e o gr\u00e1fico din\u00e2mico\u201d<\/strong><\/p><p> de \u201cPermitir que todos os usu\u00e1rios desta planilha fa\u00e7am:\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-utiliser-le-tableau-croise-dynamique-dans-une-feuille-de-calcul-protegee-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para usar a tabela din\u00e2mica em uma planilha protegida\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-37-8342fb12-627e-4263-9b8e-642248002353\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-8342fb12-627e-4263-9b8e-642248002353\"> 38. Clique duas vezes para abrir as configura\u00e7\u00f5es do campo de valor <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-37-8342fb12-627e-4263-9b8e-642248002353\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea deseja abrir as \u201cConfigura\u00e7\u00f5es de valor\u201d para uma coluna de valor espec\u00edfica\u2026<\/p><p> \u2026ENT\u00c3O\u2026 <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Conseils-sur-le-tableau-croise-dynamique-Excel-Astuces-pour-double-cliquer-pour-ouvrir-les-parametres-du-champ-de-valeur-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para clicar duas vezes para abrir as configura\u00e7\u00f5es do campo de valor\"><\/figure><\/div><p> \u2026a melhor maneira \u00e9 clicar duas vezes no cabe\u00e7alho da coluna.<\/p><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Torne suas tabelas din\u00e2micas um pouco mais perfeitas<\/h2><p> As tabelas din\u00e2micas s\u00e3o uma das maneiras mais eficazes e f\u00e1ceis de criar relat\u00f3rios. E precisamos compartilhar relacionamentos com outras pessoas o tempo todo. Antes, compartilhei algumas dicas \u00fateis que podem ajud\u00e1-lo a compartilhar uma tabela din\u00e2mica facilmente. <\/p><div id=\"ub-content-toggle-9387390b-714e-4c3f-9992-be0edc44e22e\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-9387390b-714e-4c3f-9992-be0edc44e22e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9387390b-714e-4c3f-9992-be0edc44e22e\"> 1. Reduz o tamanho de um relat\u00f3rio de tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-9387390b-714e-4c3f-9992-be0edc44e22e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Se voc\u00ea pensa assim: Quando voc\u00ea cria uma tabela din\u00e2mica do zero, o Excel cria um cache din\u00e2mico.<\/p><p> Portanto, quanto mais tabelas din\u00e2micas voc\u00ea criar do zero, mais cache din\u00e2mico o Excel criar\u00e1 e seu arquivo ter\u00e1 que armazenar mais dados.<\/p><p> Ent\u00e3o qual \u00e9 o objetivo?<\/p><p> <strong>Certifique-se de que todas as tabelas din\u00e2micas provenientes de fontes de dados tenham o mesmo cache.<\/strong><\/p><p> Mas Puneet, como eu poderia fazer isso?<\/p><p> Simples, sempre que precisar criar um segundo, terceiro ou quarto\u2026 basta copiar e colar o primeiro e fazer altera\u00e7\u00f5es nele. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-9387390b-714e-4c3f-9992-be0edc44e22e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9387390b-714e-4c3f-9992-be0edc44e22e\"> 2. Exclua os dados de origem e a tabela din\u00e2mica ainda funcionar\u00e1 bem <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-9387390b-714e-4c3f-9992-be0edc44e22e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Outra coisa que voc\u00ea pode fazer antes de enviar uma tabela din\u00e2mica para algu\u00e9m \u00e9 excluir os dados de origem.<\/p><p> Sua tabela din\u00e2mica ainda funcionar\u00e1 corretamente.<\/p><p> E, se algu\u00e9m precisar dos dados de origem, poder\u00e1 obt\u00ea-los clicando no total geral da tabela din\u00e2mica. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-9387390b-714e-4c3f-9992-be0edc44e22e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9387390b-714e-4c3f-9992-be0edc44e22e\"> 3. Salve uma tabela din\u00e2mica como uma p\u00e1gina da web [HTML] <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-9387390b-714e-4c3f-9992-be0edc44e22e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Outra maneira de compartilhar uma tabela din\u00e2mica com algu\u00e9m \u00e9 criar uma p\u00e1gina da web.<\/p><p> Sim, um arquivo HTML simples com uma tabela din\u00e2mica.<\/p><ul><li> Para fazer isso, basta salvar a pasta de trabalho como uma p\u00e1gina da web [html]. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-enregistrer-un-tableau-croise-dynamique-en-tant-que-page-Web-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para salvar uma tabela din\u00e2mica como uma p\u00e1gina da Web\"><\/figure><\/div><ul><li> Na p\u00e1gina Publicar como Web, selecione a tabela din\u00e2mica e clique em \u201cPublicar\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-enregistrer-un-tableau-croise-dynamique-en-tant-que-page-Web-en-tant-que-publication-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para salvar uma tabela din\u00e2mica como uma p\u00e1gina da Web como uma postagem\"><\/figure><\/div><p> Agora voc\u00ea pode enviar esta p\u00e1gina HTML para qualquer pessoa e ela poder\u00e1 ver a tabela din\u00e2mica (n\u00e3o edit\u00e1vel) at\u00e9 mesmo em seu celular. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-enregistrer-un-tableau-croise-dynamique-en-tant-que-fichier-HTML-de-page-Web-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para salvar uma tabela din\u00e2mica como um arquivo HTML de p\u00e1gina da Web\"><\/figure><\/div><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-9387390b-714e-4c3f-9992-be0edc44e22e\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9387390b-714e-4c3f-9992-be0edc44e22e\"> 4. Criando uma tabela din\u00e2mica por meio de uma pasta de trabalho a partir de um endere\u00e7o da Web <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-9387390b-714e-4c3f-9992-be0edc44e22e\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Suponha que voc\u00ea tenha um link da web para um arquivo Excel, como abaixo:<\/p><pre class=\"wp-block-preformatted\"> https:\/\/exceladvisor.org\/book1.xlsx<\/pre><p> Nesta pasta de trabalho voc\u00ea tem os dados e com esses dados voc\u00ea precisa criar uma tabela din\u00e2mica.<\/p><p> Para isso, POWER QUERY \u00e9 a chave.<\/p><p> <strong>Confira isto: <a href=\"https:\/\/exceladvisor.org\/pt\/solicitacao-de-energia\/\">Exemplos de Power Query + dicas e truques<\/a><\/strong><\/p><ul><li> Primeiro, v\u00e1 para a guia Dados \u279c Obter e transformar dados \u279c Da Web. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-les-tableaux-croises-dynamiques-Astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-Power-uery-en-obtenant-des-donnees-a-partir-dun-lien-Web-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para criar uma tabela din\u00e2mica usando o Power uery, obtendo dados de um link da web\"><\/figure><\/div><ul><li> Agora, na caixa de di\u00e1logo \u201cDa Web\u201d, insira o endere\u00e7o da web da pasta de trabalho e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-Power-uery-en-obtenant-des-donnees-a-partir-dun-lien-Web-ajouter-une-URL-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Truques para criar uma tabela din\u00e2mica usando o Power uery, obtendo dados de um link da Web Adicionar URL\"><\/figure><\/div><ul><li> Depois disso, selecione a planilha e clique em \u201cCarregar para\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-creer-un-tableau-croise-dynamique-a-laide-de-power-uery-en-obtenant-des-donnees-a-partir-dun-lien-Web-selectionner-une-feuille-de-calcul-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica, dicas do Excel, truques para criar uma tabela din\u00e2mica usando o Power Uery, obtendo dados de um link da web, selecione uma planilha\"><\/figure><\/div><ul><li> Em seguida, selecione o relat\u00f3rio de tabela din\u00e2mica e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel.png\" sizes=\"\" srcset=\"\" alt=\"excel-dicas-de-tabela-din\u00e2mica-truques-paracriar-tabela-din\u00e2mica-usando-power-uery-por-obter-dados-de-um-link-da-web-adicionar-url\"><\/figure><\/div><p> Neste ponto, voc\u00ea tem uma tabela din\u00e2mica em branco conectada \u00e0 pasta de trabalho a partir do endere\u00e7o da Web inserido.<\/p><p> Agora voc\u00ea pode criar uma tabela din\u00e2mica como desejar.<\/p><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> O que voc\u00ea pode fazer em uma tabela din\u00e2mica com CF<\/h2><p> Para mim, a formata\u00e7\u00e3o condicional \u00e9 uma formata\u00e7\u00e3o inteligente. Tenho certeza que voc\u00ea concorda com isso. Bem, quando se trata de tabela din\u00e2mica, CF funciona perfeitamente. <\/p><div id=\"ub-content-toggle-1804045a-7d4b-4bcc-951b-9921560ab0f5\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-1804045a-7d4b-4bcc-951b-9921560ab0f5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-1804045a-7d4b-4bcc-951b-9921560ab0f5\"> 1. Aplica\u00e7\u00e3o de op\u00e7\u00f5es gerais de CF <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-1804045a-7d4b-4bcc-951b-9921560ab0f5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Existem todas as op\u00e7\u00f5es de CF dispon\u00edveis para uso com uma tabela din\u00e2mica.<\/p><p> \u279c aqui est\u00e1 o guia que pode ajud\u00e1-lo a aprender <a href=\"https:\/\/exceladvisor.org\/pt\/aplicar-formatacao-condicional\/\">todas as diferentes maneiras de usar CF em tabelas din\u00e2micas<\/a> . <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-1804045a-7d4b-4bcc-951b-9921560ab0f5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-1804045a-7d4b-4bcc-951b-9921560ab0f5\"> 2. Destaque os 10 principais valores <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-1804045a-7d4b-4bcc-951b-9921560ab0f5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Em vez de filtrar, voc\u00ea pode destacar os 10 primeiros valores em uma tabela din\u00e2mica.<\/p><p> Para fazer isso, voc\u00ea deve usar a formata\u00e7\u00e3o condicional.<\/p><p> As etapas est\u00e3o abaixo:<\/p><ul><li> Selecione uma das c\u00e9lulas na coluna de valor da sua tabela din\u00e2mica.<\/li><li> V\u00e1 para a guia In\u00edcio \u279c Estilos \u279c Formata\u00e7\u00e3o Condicional.<\/li><li> Agora em Formata\u00e7\u00e3o Condicional, v\u00e1 para Regras Superiores\/Inferiores \u279c 10 Principais Elementos. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-appliquer-les-10-meilleures-options-de-mise-en-forme-conditionnelle-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para aplicar as 10 principais op\u00e7\u00f5es de formata\u00e7\u00e3o condicional\"><\/figure><\/div><ul><li> Selecione a cor na janela que voc\u00ea possui. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-appliquer-les-10-meilleures-options-de-mise-en-forme-conditionnelle-selectionner-la-couleur-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica, dicas do Excel, truques para aplicar as 10 principais op\u00e7\u00f5es de formata\u00e7\u00e3o condicional, selecione a cor\"><\/figure><\/div><ul><li> E no final clique em OK.<\/li><\/ul><p> Esta op\u00e7\u00e3o \u00e9 muito \u00fatil ao criar relat\u00f3rios r\u00e1pidos com uma tabela din\u00e2mica e uma vez que voc\u00ea. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-1804045a-7d4b-4bcc-951b-9921560ab0f5\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-1804045a-7d4b-4bcc-951b-9921560ab0f5\"> 3. Remova CF de uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-1804045a-7d4b-4bcc-951b-9921560ab0f5\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Voc\u00ea pode simplesmente remover a formata\u00e7\u00e3o condicional de uma tabela din\u00e2mica seguindo as etapas abaixo:<\/p><ul><li> Primeiro, selecione uma das c\u00e9lulas da tabela din\u00e2mica.<\/li><li> Depois disso, v\u00e1 para a aba Home \u279c Estilos \u279c Formata\u00e7\u00e3o Condicional \u279c Limpar Regras \u279c \u201cLimpar as regras para esta tabela din\u00e2mica\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-effacer-tout-le-formatage-conditionnel-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para limpar toda a formata\u00e7\u00e3o condicional\"><\/figure><\/div><p> Se voc\u00ea tiver v\u00e1rias tabelas din\u00e2micas, dever\u00e1 excluir os CFs um por um.<\/p><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Use gr\u00e1ficos din\u00e2micos com tabelas din\u00e2micas para visualizar seus relat\u00f3rios<\/h2><p> Sou um grande f\u00e3 da tabela din\u00e2mica.<\/p><p> Se voc\u00ea souber usar uma tabela din\u00e2mica corretamente, poder\u00e1 aproveitar ao m\u00e1ximo uma das melhores ferramentas do Excel.<\/p><p> Aqui est\u00e3o algumas dicas que voc\u00ea pode usar para se tornar um PRO de tabela din\u00e2mica rapidamente e se quiser saber tudo sobre uma tabela din\u00e2mica <a href=\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-2\/\" data-wpil=\"url\">, voc\u00ea pode aprender com este guia<\/a> . <\/p><div id=\"ub-content-toggle-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"> 1. Inserindo uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Compartilhei um atalho de teclado simples para <a href=\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-2\/\" data-wpil=\"url\">inserir uma tabela din\u00e2mica<\/a> , mas voc\u00ea tamb\u00e9m usa as etapas abaixo:<\/p><ul><li> Selecione uma c\u00e9lula na tabela din\u00e2mica e <strong><span style=\"color: #000000;\">v\u00e1 para \u201cAba Analisar\u201d<\/span><\/strong> .<\/li><li> Na aba \u201cAnalisar\u201d, clique em \u201cGr\u00e1fico Din\u00e2mico\u201d. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-pour-inserer-un-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel, truques para inserir uma tabela din\u00e2mica\"><\/figure><\/div><p> Ele criar\u00e1 instantaneamente uma tabela din\u00e2mica a partir da tabela din\u00e2mica que voc\u00ea possui. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"> 2. Criando um histograma usando um gr\u00e1fico din\u00e2mico e uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Uma tabela din\u00e2mica e um gr\u00e1fico din\u00e2mico s\u00e3o minha forma favorita de criar um histograma no Excel. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-Conseils-sur-le-tableau-croise-dynamique-Astuces-pour-creer-un-histogramme-a-laide-dun-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para criar um histograma usando uma tabela din\u00e2mica\"><\/figure><\/div><p> <a href=\"https:\/\/exceladvisor.org\/pt\/histograma\/\">Aqui est\u00e1 um guia passo a passo para isso.<\/a> <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"> 3. Desative os bot\u00f5es da tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Quando voc\u00ea insere uma nova tabela din\u00e2mica, ela vem com bot\u00f5es para filtr\u00e1-la que \u00e0s vezes n\u00e3o s\u00e3o muito \u00fateis.<\/p><p> E se voc\u00ea pensa assim, voc\u00ea pode esconder todos ou alguns deles. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/conseils-de-tableau-croise-dynamique-excel-astuces-un-tableau-croise-dynamique-avec-des-boutons-de-filtre-1.png\" sizes=\"\" srcset=\"\" alt=\"dicas de tabela din\u00e2mica dicas do Excel uma tabela din\u00e2mica com bot\u00f5es de filtro\"><\/figure><\/div><p> <strong><span style=\"color: #000000;\">Clique com o bot\u00e3o direito no bot\u00e3o<\/span><\/strong> e selecione \u201cOcultar bot\u00e3o de campo de valor no gr\u00e1fico\u201d para ocultar o bot\u00e3o selecionado ou clique em \u201cOcultar todos os bot\u00f5es de campo no gr\u00e1fico\u201d para ocultar todos os bot\u00f5es. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-tableau-croise-dynamique-conseils-astuces-masquer-les-boutons-de-filtre-du-tableau-croise-dynamique-1.png\" sizes=\"\" srcset=\"\" alt=\"Truques de dicas de tabela din\u00e2mica do Excel Ocultar bot\u00f5es de filtro de tabela din\u00e2mica\"><\/figure><\/div><p> Quando voc\u00ea oculta todos os bot\u00f5es em uma Tabela Din\u00e2mica, ele tamb\u00e9m oculta o bot\u00e3o de filtro na parte inferior do gr\u00e1fico <strong><span style=\"color: #000000;\">, mas voc\u00ea ainda pode filtr\u00e1-lo<\/span><\/strong> usando o filtro de Tabela Din\u00e2mica, Slicer ou Linha do Tempo. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\"> 4. Adicione uma tabela din\u00e2mica ao PowerPoint <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-cfe2bfae-33d9-40f3-94c7-eae98cc301fc\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> Aqui est\u00e3o as etapas simples para colar uma tabela din\u00e2mica em um slide do PowerPoint.<\/p><ul><li> Primeiro, selecione uma tabela din\u00e2mica e copie-a.<\/li><li> Depois disso, v\u00e1 para o slide do PowerPoint e <strong><span style=\"color: #000000;\">abra Op\u00e7\u00f5es de colagem especiais<\/span><\/strong> . <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-copier-le-tableau-croise-dynamique-vers-power-point-slide-open-psate-special-1.png\" sizes=\"\" srcset=\"\" alt=\"tabela din\u00e2mica dicas do Excel truques para copiar uma tabela din\u00e2mica para uma apresenta\u00e7\u00e3o de slides em power point abrir colar especial\"><\/figure><\/div><ul><li> Agora, na caixa de di\u00e1logo de colagem especial, <strong><span style=\"color: #000000;\">selecione \u201cObjeto gr\u00e1fico do Microsoft Excel\u201d<\/span><\/strong> e clique em OK. <\/li><\/ul><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableau-croise-dynamique-excel-conseils-astuces-pour-copier-un-tableau-croise-dynamique-vers-une-diapositive-power-point-selectionner-lobjet-graphique-microsoft-excel-1.png\" sizes=\"\" srcset=\"\" alt=\"Dicas de tabela din\u00e2mica do Excel Dicas para copiar uma tabela din\u00e2mica para um slide do Power Point Selecione um objeto gr\u00e1fico do Microsoft Excel\"><\/figure><\/div><p> Para fazer altera\u00e7\u00f5es na tabela din\u00e2mica, voc\u00ea precisa clicar duas vezes nela.<\/p><\/div><\/div><\/div><h2 class=\"wp-block-heading\"> Atalhos de teclado para aumentar seu trabalho na tabela din\u00e2mica<\/h2><p> Todos n\u00f3s amamos atalhos de teclado. CERTO? Listei aqui alguns dos atalhos de teclado comuns, mas \u00fateis, que voc\u00ea pode usar para acelerar o trabalho da tabela din\u00e2mica. <\/p><div id=\"ub-content-toggle-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle\" data-mobilecollapse=\"false\" data-desktopcollapse=\"true\"><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-0-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 1. Crie uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-0-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt + N + V<\/strong><\/p><p> Para usar esta tecla de atalho, certifique-se de ter selecionado os dados de origem ou de que a c\u00e9lula ativa seja dos dados de origem. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-1-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 2. Agrupar itens selecionados da tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-1-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt + Shift + Seta para a direita<\/strong><\/p><p> Digamos que voc\u00ea tenha uma tabela din\u00e2mica com meses e queira agrupar os primeiros seis ou os \u00faltimos seis meses.<\/p><p> Tudo que voc\u00ea precisa fazer \u00e9 selecionar essas seis c\u00e9lulas e usar esta tecla de atalho. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-2-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 3. Desagrupar itens selecionados da tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-2-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt + Shift + Seta para a esquerda<\/strong><\/p><p> Assim como voc\u00ea pode criar um grupo de itens, este atalho ajuda a desagrupar esses itens do grupo. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-3-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 4. Oculte o item ou campo selecionado <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-3-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Ctrl + \u2013<\/strong><\/p><p> Esta tecla de atalho simplesmente ocultar\u00e1 as c\u00e9lulas selecionadas.<\/p><p> Na verdade, ele n\u00e3o oculta as c\u00e9lulas, mas as filtra, o que voc\u00ea pode limpar nas op\u00e7\u00f5es de filtros. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-4-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 5. Abra a janela Campo Calculado <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-4-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Ctrl + \u2013<\/strong><\/p><p> Para usar esta tecla de atalho, voc\u00ea deve selecionar uma c\u00e9lula na coluna do campo de valor.<\/p><p> E ao pressionar esta tecla de atalho, abre a janela <strong><span style=\"color: #000000;\">\u201c<\/span><\/strong> <a href=\"https:\/\/exceladvisor.org\/pt\/calculo-em-tabela-dinamica\/\"><strong><span style=\"color: #000000;\">Campo Calculado<\/span><\/strong><\/a> <strong><span style=\"color: #000000;\">\u201d<\/span><\/strong> . <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-5-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> Abra o antigo Assistente de Tabela Din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-5-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt + D e P<\/strong><\/p><p> Neste atalho de teclado, voc\u00ea deve pressionar as teclas posteriormente. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-6-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 7. Abra a lista de campos da c\u00e9lula ativa <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-6-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt + seta para baixo<\/strong><\/p><p> Esta chave abre a lista de campos. <\/p><\/div><\/div><div class=\"wp-block-ub-content-toggle-accordion\"><div class=\"wp-block-ub-content-toggle-accordion-title-wrap\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"ub-content-toggle-panel-7-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"><h3 class=\"wp-block-ub-content-toggle-accordion-title ub-content-toggle-title-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\"> 8. Insira um gr\u00e1fico din\u00e2mico de uma tabela din\u00e2mica <\/h3><div class=\"wp-block-ub-content-toggle-accordion-toggle-wrap right\"><\/div><\/div><div id=\"ub-content-toggle-panel-7-9ee80016-730a-4eaf-965d-e3a3d1c1c6c2\" class=\"wp-block-ub-content-toggle-accordion-content-wrap ub-hide\" role=\"region\"><p> <strong>Alt+F1<\/strong><\/p><p> Para usar este atalho de teclado, voc\u00ea deve selecionar uma c\u00e9lula na tabela din\u00e2mica. Esta chave insere uma tabela din\u00e2mica na planilha existente.<\/p><p> <strong>F11<\/strong><\/p><p> E, se quiser inserir um piv\u00f4 em uma nova planilha, basta usar a chave acima. <\/p><\/div><\/div><\/div><ul id=\"ub_styled_list-ee33a0bf-286a-454d-a920-a3a0db3e5da0\" class=\"ub_styled_list\"><li class=\"ub_styled_list_item\"> <a href=\"https:\/\/exceladvisor.org\/pt\/atalhos-do-teclado\/\"><strong>Folha de refer\u00eancias dos atalhos de teclado do Excel<\/strong><\/a><\/li><\/ul><h2 class=\"wp-block-heading\"> No final<\/h2><p> Como eu disse, as tabelas din\u00e2micas s\u00e3o uma daquelas ferramentas que podem ajud\u00e1-lo a melhorar a gera\u00e7\u00e3o de relat\u00f3rios e a an\u00e1lise de dados rapidamente.<\/p><p> E com essas dicas e truques voc\u00ea pode economizar ainda mais tempo. Se voc\u00ea me perguntar, quero que comece a usar pelo menos 10 dicas primeiro, depois passe para as pr\u00f3ximas 10 e assim por diante.<\/p><p> Mas agora voc\u00ea tem que me dizer uma coisa: <strong>qual \u00e9 a sua dica favorita de tabela din\u00e2mica?<\/strong><\/p><h2 class=\"wp-block-heading\"> <strong>N\u00e3o deixe de ler estes<\/strong> <\/h2><div class=\"wp-block-columns is-layout-flex wp-container-108\"><div class=\"wp-block-column is-layout-flow\"><ul><li> <a href=\"https:\/\/exceladvisor.org\/pt\/adicionar-excluir-total-geral\/\">Adicionar-Remover Total Geral em uma Tabela Din\u00e2mica<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/total-cumulativo\/\">Adicionar um total acumulado a uma tabela din\u00e2mica<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/faixa-de-atualizacao-automatica\/\">Atualizar automaticamente uma tabela din\u00e2mica<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/calculo-em-tabela-dinamica\/\">F\u00f3rmulas em uma tabela din\u00e2mica<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/alterar-fonte-de-dados\/\">Alterar a fonte de dados da tabela din\u00e2mica<\/a><\/li><\/ul><\/div><div class=\"wp-block-column is-layout-flow\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-351","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais de 100 dicas para tabela din\u00e2mica 2023<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 100 dicas para tabela din\u00e2mica 2023\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:51:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/\",\"name\":\"Mais de 100 dicas para tabela din\u00e2mica 2023\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png\",\"datePublished\":\"2023-11-01T06:50:26+00:00\",\"dateModified\":\"2023-12-06T11:51:05+00:00\",\"description\":\"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais de 100 truques ocultos de tabela din\u00e2mica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 100 dicas para tabela din\u00e2mica 2023","description":"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/","og_locale":"pt_PT","og_type":"article","og_title":"Mais de 100 dicas para tabela din\u00e2mica 2023","og_description":"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas","og_url":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:51:05+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/","url":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/","name":"Mais de 100 dicas para tabela din\u00e2mica 2023","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png","datePublished":"2023-11-01T06:50:26+00:00","dateModified":"2023-12-06T11:51:05+00:00","description":"Se voc\u00ea deseja levar suas habilidades de Excel a um n\u00edvel totalmente novo, voc\u00ea precisa melhorar em tabelas din\u00e2micas","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/tableaux-croises-dynamiques-Excel-trucs-et-astuces-pour-supprimer-les-lignes-et-les-colonnes-balnk-des-donnees-source-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/tabela-dinamica-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Mais de 100 truques ocultos de tabela din\u00e2mica"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/351\/revisions"}],"predecessor-version":[{"id":1444,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/351\/revisions\/1444"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}