{"id":396,"date":"2023-10-30T13:25:43","date_gmt":"2023-10-30T13:25:43","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/"},"modified":"2023-12-06T11:35:43","modified_gmt":"2023-12-06T11:35:43","slug":"conte-as-palavras","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/","title":{"rendered":"Como contar palavras no excel?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-194116748\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-1120381011\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>H\u00e1 uma op\u00e7\u00e3o que sempre desejei que o Excel tivesse: contar o n\u00famero de palavras em uma c\u00e9lula. Se voc\u00ea estiver trabalhando no MS Word, h\u00e1 uma op\u00e7\u00e3o integrada na barra de status que mostra quantas palavras existem na planilha. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png\" sizes=\"\" srcset=\"\" alt=\"existe uma op\u00e7\u00e3o no word para contar palavras, mas n\u00e3o no excel\"><\/figure><\/div><p> Mas quando se trata de Excel, n\u00e3o existe essa op\u00e7\u00e3o de contar palavras. Voc\u00ea pode contar o <a style=\"outline: none;\" href=\"https:\/\/exceladvisor.org\/pt\/contar-celulas-com-texto\/\">n\u00famero de c\u00e9lulas que cont\u00eam texto,<\/a> mas nenhuma palavra real.<\/p><p> Como voc\u00ea sabe, <a style=\"outline: none;\" href=\"https:\/\/exceladvisor.org\/pt\/funcoes-do-excel\/\">no Excel temos fun\u00e7\u00f5es<\/a> e voc\u00ea pode us\u00e1-las para calcular quase tudo. Voc\u00ea pode criar uma f\u00f3rmula que conte as palavras em uma c\u00e9lula.<\/p><p> Hoje neste artigo voc\u00ea aprender\u00e1 como contar palavras no Excel a partir de uma \u00fanica c\u00e9lula, de um intervalo de c\u00e9lulas ou at\u00e9 mesmo de toda a planilha. E tamb\u00e9m mostrarei como contar uma palavra espec\u00edfica em um intervalo de c\u00e9lulas.<\/p><h2 id=\"0-1-count-words-from-a-single-cell\" class=\"wp-block-heading\"> 1. Conte palavras em uma \u00fanica c\u00e9lula<\/h2><p> Para contar as palavras em uma c\u00e9lula, voc\u00ea deve <span style=\"color: #000000;\">combinar a<\/span> fun\u00e7\u00e3o LEN com a <span style=\"color: #000000;\">fun\u00e7\u00e3o SUBSTITUTE<\/span> . E a f\u00f3rmula ser\u00e1 (O texto est\u00e1 na c\u00e9lula A1): <\/p><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=LEN(A1)-LEN(SUBSTITUTE(A1,\" \",\"\"))+1<\/code><\/pre><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/formule-pour-compter-le-mot-dans-Excel-en-utilisant-le-substitut-len.png\" sizes=\"\" srcset=\"\" alt=\"f\u00f3rmula para contar palavras no Excel usando substituto de len\"><\/figure><\/div><p> Quando voc\u00ea se refere a uma c\u00e9lula usando esta f\u00f3rmula, ela retornar\u00e1 7 no resultado. E sim, voc\u00ea tem um total de 7 palavras na c\u00e9lula.<\/p><h3 id=\"1-how-it-works\" class=\"wp-block-heading\"> Como funciona<\/h3><p> Antes de entrarmos nesta f\u00f3rmula, pense desta forma. Em uma frase normal, se voc\u00ea tiver oito palavras, com certeza ter\u00e1 7 espa\u00e7os nessas palavras. CERTO?<\/p><p> Isso significa que voc\u00ea sempre ter\u00e1 uma palavra a mais do que espa\u00e7os. A ideia \u00e9 simples: se quiser contar palavras, conte os espa\u00e7os e some um. Para entender esta f\u00f3rmula, \u00e9 necess\u00e1rio dividi-la em tr\u00eas partes. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/comment-fonctionne-la-formule-pour-compter-le-mot-dans-Excel-en-utilisant-le-substitut-len.png\" sizes=\"\" srcset=\"\" alt=\"como funciona a f\u00f3rmula para contar palavras no Excel usando substituto len\"><\/figure><\/div><p> Na primeira parte, voc\u00ea usou a fun\u00e7\u00e3o LEN para contar o n\u00famero de caracteres na c\u00e9lula A1. E na segunda e terceira partes, voc\u00ea combinou SUBSTITUTE com LEN para <a href=\"https:\/\/exceladvisor.org\/pt\/remover-espacos-extras\/\">remover os espa\u00e7os da c\u00e9lula<\/a> e depois contar os caracteres. Neste ponto voc\u00ea tem uma equa\u00e7\u00e3o como esta. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/equation-de-formule-pour-compter-les-mots-dans-excel.png\" sizes=\"\" srcset=\"\" alt=\"equa\u00e7\u00e3o de f\u00f3rmula para contar palavras no Excel\"><\/figure><\/div><p> O n\u00famero total de caracteres com espa\u00e7os e o n\u00famero total de caracteres sem espa\u00e7os. E ao subtrair os dois n\u00fameros obt\u00e9m o n\u00famero de espa\u00e7os e no final voc\u00ea precisa somar um. Ele retorna 7 no resultado, que \u00e9 o n\u00famero total de palavras na c\u00e9lula.<\/p><p class=\"has-text-align-left qt-tip\"> <strong>Importante<\/strong> : Ao usar a f\u00f3rmula acima, ela retornar\u00e1 1 mesmo que a c\u00e9lula esteja vazia, por isso \u00e9 melhor envolv\u00ea-la com a fun\u00e7\u00e3o IF para evitar esse problema. <\/p><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=IF(ISBLANK(A2),0,LEN(A2)-LEN(SUBSTITUTE(A2,\" \",\"\"))+1)<\/code><\/pre><p class=\"has-text-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/compter-les-mots-dans-Excel-utiliser-si-lorsque-la-cellule-est-vide.png\" sizes=\"auto, \" srcset=\"\" alt=\"contar palavras no Excel use se quando a c\u00e9lula estiver vazia\" width=\"646\" height=\"130\" data-attachment-id=\"14725\"><\/p><p> Esta f\u00f3rmula verificar\u00e1 a c\u00e9lula primeiro e retornar\u00e1 a contagem de palavras apenas se houver um valor na c\u00e9lula.<\/p><h2 id=\"2-2-using-a-udf\" class=\"wp-block-heading\"> 2. Use uma UDF<\/h2><p> Al\u00e9m das f\u00f3rmulas acima, escrevi um pequeno c\u00f3digo para <a href=\"https:\/\/exceladvisor.org\/pt\/funcao-definida-pelo-usuario-2\/\">criar uma UDF<\/a> para isso. Este c\u00f3digo o ajudar\u00e1 a criar uma fun\u00e7\u00e3o personalizada que simplesmente retornar\u00e1 a contagem de palavras. Resumindo, voc\u00ea n\u00e3o precisa combinar fun\u00e7\u00f5es.<\/p><pre class=\"wp-block-code\"> <code class=\"language-visual-basic line-numbers\" lang=\"visual-basic\">Function MyWordCount(rng As Range) As Integer MyWordCount = UBound(Split(rng.Value, \" \"), 1) + 1 End Function<\/code><\/pre><p> Deixe-me dizer como us\u00e1-lo.<\/p><ol><li> Primeiro, insira este c\u00f3digo no editor VBA. <br><img decoding=\"async\" title=\"adicionar-c\u00f3digo-udf-ao-vbe-para-contar-palavras-na-c\u00e9lula do Excel\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/ajouter-le-code-udf-a-vbe-pour-compter-les-mots-dans-la-cellule-excel.png\" sizes=\"\" srcset=\"\" alt=\"add udf code to vbe to count words in excel cell\"><\/li><li> E ent\u00e3o volte para sua planilha e digite \u201c=MyWordCount(\u201d e consulte a c\u00e9lula onde voc\u00ea tem um valor.<\/li><\/ol><p> E retornar\u00e1 a contagem de palavras. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/udf-pour-compter-le-mot-dans-excel-en-utilisant-le-substitut-len.png\" sizes=\"\" srcset=\"\" alt=\"udf para contar palavras no Excel usando substituto de len\"><\/figure><\/div><p> <em>Relacionado: <a href=\"https:\/\/exceladvisor.org\/pt\/barra-de-formulas-do-excel\/\">Barra de F\u00f3rmulas no Excel<\/a><\/em><\/p><h2 id=\"3-3-count-words-from-a-range-of-cells\" class=\"wp-block-heading\"> 3. Conte palavras em um intervalo de c\u00e9lulas<\/h2><p> Agora vamos passar para o pr\u00f3ximo n\u00edvel. E aqui voc\u00ea tem que contar palavras de um intervalo de c\u00e9lulas em vez de uma \u00fanica c\u00e9lula. A <strong><span style=\"color: #000000;\">boa not\u00edcia \u00e9 que<\/span><\/strong> voc\u00ea s\u00f3 precisa usar a mesma f\u00f3rmula (apenas uma simples altera\u00e7\u00e3o) que usou acima. E a f\u00f3rmula ser\u00e1: <\/p><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=SUMPRODUCT(LEN(A1:A11)-LEN(SUBSTITUTE(A1:A11,\" \",\"\"))+1)<\/code><\/pre><p class=\"has-text-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/formule-pour-compter-le-mot-dans-Excel-a-partir-de-la-plage-de-lignes-de-colonne.png\" sizes=\"auto, \" srcset=\"\" alt=\"f\u00f3rmula para contar palavras no Excel a partir do intervalo de linhas de colunas\" width=\"683\" height=\"367\" data-attachment-id=\"14729\"><\/p><p> Na f\u00f3rmula acima, A1:A11 \u00e9 o intervalo de c\u00e9lulas e quando voc\u00ea insere a f\u00f3rmula, ela retorna 77 no resultado.<\/p><h3 id=\"4-how-it-works\" class=\"wp-block-heading\"> Como funciona<\/h3><p> Esta f\u00f3rmula funciona da mesma forma que o primeiro m\u00e9todo, mas \u00e9 apenas um pequeno passo em frente. A \u00fanica diferen\u00e7a \u00e9 que voc\u00ea o envolveu em SUMPRODUCT e se referiu ao intervalo inteiro em vez de apenas a uma c\u00e9lula. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/comment-sumproduct-fonctionne-pour-compter-le-mot-dans-excel.png\" sizes=\"auto, \" srcset=\"\" alt=\"como funciona o sumproduct para contar palavras no Excel\" width=\"532\" height=\"26\"><\/figure><\/div><p> Voc\u00ea sabia que SUMPRODUCT pode aceitar tabelas? Ent\u00e3o, quando voc\u00ea o usa, ele retorna um array onde voc\u00ea tem uma contagem de palavras para cada c\u00e9lula. E no final soma esses n\u00fameros e informa a quantidade de palavras na coluna.<\/p><h2 id=\"5-4-word-count-from-entire-worksheet-\" class=\"wp-block-heading\"> 4. Contagem de palavras de toda a planilha<\/h2><p> Este c\u00f3digo \u00e9 um dos c\u00f3digos de macro \u00fateis que uso em meu trabalho e pode ajud\u00e1-lo a contar todas as palavras em uma planilha.<\/p><pre class=\"wp-block-code\"> <code class=\"language-visual-basic line-numbers\" lang=\"visual-basic\">Sub Word_Count_Worksheet() Dim WordCnt As Long Dim rng As Range Dim S As String Dim N As Long For Each rng In ActiveSheet.UsedRange.Cells S = Application.WorksheetFunction.Trim(rng.Text) N = 0 If S &lt;&gt; vbNullString Then N = Len(S) \u2013 Len(Replace(S, \" \", \"\")) + 1 End If WordCnt = WordCnt + N Next rng MsgBox \"There are total \" &amp; Format(WordCnt, \"#,##0\") &amp; \" words in the active worksheet\" End Sub<\/code><\/pre><p> Ao execut\u00e1-lo, <a href=\"https:\/\/exceladvisor.org\/pt\/caixa-de-mensagens-vba\/\" target=\"\" rel=\"noopener noreferrer\" data-tcb-events=\"\">ele exibir\u00e1 uma caixa de mensagem<\/a> com a quantidade de palavras que voc\u00ea possui na planilha ativa. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/code-vba-pour-compter-les-mots-dans-excel-en-utilisant-vba.png\" sizes=\"\" srcset=\"\" alt=\"c\u00f3digo vba para contar palavras no excel usando vba\"><\/figure><\/div><p> <em>Relacionado: <a href=\"https:\/\/exceladvisor.org\/pt\/vba\/\">O que \u00e9 VBA no Excel<\/a><\/em><\/p><h2 id=\"6-5-count-a-specific-wordtext-string-from-a-range\" class=\"wp-block-heading\"> 5. Conte uma palavra\/sequ\u00eancia de texto espec\u00edfica de um intervalo<\/h2><p> Aqui voc\u00ea tem uma situa\u00e7\u00e3o diferente. Suponha que voc\u00ea precise contar uma palavra espec\u00edfica em um intervalo de c\u00e9lulas ou verificar o n\u00famero de vezes que um valor aparece em uma coluna.<\/p><p> Vejamos este exemplo: Abaixo voc\u00ea tem um intervalo de quatro c\u00e9lulas e desse intervalo voc\u00ea precisa contar o n\u00famero de <strong><span style=\"color: #000000;\">ocorr\u00eancias da palavra &#8220;segunda-feira&#8221;<\/span><\/strong> .<\/p><p> Para isso, a f\u00f3rmula \u00e9: <\/p><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=SUMPRODUCT((LEN(D6:D9)-LEN(SUBSTITUTE(D6:D9,\"Monday\",\"\")))\/LEN(\"Monday\"))<\/code><\/pre><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/compter-les-mots-dans-Excel-specifique-avec-la-formule-sumproduct.png\" sizes=\"\" srcset=\"\" alt=\"contar palavras no Excel espec\u00edfico com f\u00f3rmula somaproduto\"><\/figure><\/div><p> E quando voc\u00ea digita, a contagem regressiva volta at\u00e9 a palavra \u201csegunda-feira\u201d. S\u00e3o 4.<\/p><p class=\"qt-tip\"> <strong>Importante:<\/strong> retorna o n\u00famero de palavras (frequ\u00eancia das palavras) do intervalo <span style=\"color: #000000;\">e n\u00e3o o n\u00famero de c\u00e9lulas<\/span> que cont\u00e9m essa palavra. Segunda-feira est\u00e1 l\u00e1 quatro vezes em tr\u00eas celas.<\/p><h3 id=\"7-how-it-works\" class=\"wp-block-heading\"> Como funciona<\/h3><p> Para entender essa fun\u00e7\u00e3o, novamente, \u00e9 necess\u00e1rio dividi-la em quatro partes. Na primeira parte, a fun\u00e7\u00e3o LEN retorna um array com o n\u00famero de caracteres nas c\u00e9lulas. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/utiliser-la-formule-sumproduct-pour-compter-un-mot-specifique-a-partir-dune-plage-1.png\" sizes=\"\" srcset=\"\" alt=\"use a f\u00f3rmula somaproduto para contar uma palavra espec\u00edfica em um intervalo 1\"><\/figure><\/div><p> A segunda parte retorna uma matriz de contagens de caracteres de c\u00e9lulas, removendo a palavra &#8220;segunda-feira&#8221;. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/utiliser-la-formule-sumproduct-pour-compter-un-mot-specifique-a-partir-dune-plage-2.png\" sizes=\"\" srcset=\"\" alt=\"use a f\u00f3rmula somaproduto para contar uma palavra espec\u00edfica em um intervalo 2\"><\/figure><\/div><p> Na terceira parte, a fun\u00e7\u00e3o LEN retorna o comprimento em caracteres da palavra-chave \u201csegunda-feira\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/utiliser-la-formule-sumproduct-pour-compter-un-mot-specifique-a-partir-dune-plage-3.png\" sizes=\"\" srcset=\"\" alt=\"use a f\u00f3rmula somaproduto para contar uma palavra espec\u00edfica em um intervalo 3\"><\/figure><\/div><p> Depois disso, subtraia a primeira parte da segunda parte, depois divida pela terceira parte, retorna um array com a quantidade de palavras \u201csegunda-feira\u201d de cada c\u00e9lula. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/utiliser-la-formule-sumproduct-pour-compter-un-mot-specifique-a-partir-dune-plage-4.png\" sizes=\"\" srcset=\"\" alt=\"use a f\u00f3rmula somaproduto para contar uma palavra espec\u00edfica em um intervalo 4\"><\/figure><\/div><p> Na quarta parte, SUMPRODUCT retorna a soma deste array e fornece o n\u00famero de \u201csegundas-feiras\u201d no intervalo. <\/p><div class=\"gb-container gb-container-52dfcee1 gb-container-sample-file\"><h2 class=\"gb-headline gb-headline-e289c143 gb-headline-text gb-headline-4f7959c2\"> Obtenha o arquivo Excel<\/h2><p> <a class=\"gb-button gb-button-e88d6bee gb-button-text gb-button-button1\" href=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/compter-les-mots-2.zip\" rel=\"nofollow\">Download<\/a><\/p><\/div><h2 id=\"9-conclusion\" class=\"wp-block-heading\"> Conclus\u00e3o<\/h2><p> Sempre que voc\u00ea digita texto em uma c\u00e9lula ou intervalo de c\u00e9lulas, pode usar esses m\u00e9todos para controlar a contagem de palavras. Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos excelentes.<\/p><p> Qual m\u00e9todo voc\u00ea mais gosta? Certifique-se de compartilhar suas id\u00e9ias comigo na se\u00e7\u00e3o de coment\u00e1rios, eu adoraria ouvir de voc\u00ea. E <strong><span style=\"color: #ea493f;\">n\u00e3o esque\u00e7a de compartilhar esse post<\/span><\/strong> com seus amigos, tenho certeza que eles v\u00e3o gostar.<\/p><div class=\"gb-container gb-container-0df56012 gb-container-mt\"> <a class=\"gb-button gb-button-f9f432f4 gb-button-text gb-button-mt-button\" href=\"https:\/\/exceladvisor.org\/pt\/formulas\/\">Lista de f\u00f3rmulas do Excel<\/a><h2 class=\"gb-headline gb-headline-233444e8 gb-headline-text gb-headline-mt-heading\"> F\u00f3rmulas relacionadas <\/h2><div class=\"gb-grid-wrapper gb-grid-wrapper-a16fa65c gb-grid-wrapper-mt-grid\"><div class=\"gb-grid-column gb-grid-column-50d07e0d\"><div class=\"gb-container gb-container-50d07e0d\"><ul><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-celulas-com-texto\/\">Conte c\u00e9lulas com texto no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-caracteres-especificos\/\">Conte caracteres espec\u00edficos no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-o-numero-total-de-celulas\/\">Conte o n\u00famero total de c\u00e9lulas em um intervalo no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-valores-unicos-1\/\">Conte valores \u00fanicos no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/contar-contra-contar\/\">CONTAGEM versus CONTAGEM<\/a> <\/li><\/ul><\/div><\/div><div class=\"gb-grid-column gb-grid-column-5b4a0cf9\"><div class=\"gb-container gb-container-5b4a0cf9\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-396","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7Como contar palavras no Excel? (Tutorial 2023)<\/title>\n<meta name=\"description\" content=\"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7Como contar palavras no Excel? (Tutorial 2023)\" \/>\n<meta property=\"og:description\" content=\"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:35:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/\",\"name\":\"\u25b7Como contar palavras no Excel? (Tutorial 2023)\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png\",\"datePublished\":\"2023-10-30T13:25:43+00:00\",\"dateModified\":\"2023-12-06T11:35:43+00:00\",\"description\":\"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como contar palavras no excel?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7Como contar palavras no Excel? (Tutorial 2023)","description":"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/","og_locale":"pt_PT","og_type":"article","og_title":"\u25b7Como contar palavras no Excel? (Tutorial 2023)","og_description":"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos","og_url":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:35:43+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/","url":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/","name":"\u25b7Como contar palavras no Excel? (Tutorial 2023)","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png","datePublished":"2023-10-30T13:25:43+00:00","dateModified":"2023-12-06T11:35:43+00:00","description":"Desejo que um dia no futuro o Excel tenha essa op\u00e7\u00e3o de contar palavras. Mas, por enquanto, voc\u00ea tem todos esses m\u00e9todos","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/il-y-a-une-option-dans-word-pour-compter-les-mots-mais-pas-dans-excel.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/conte-as-palavras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como contar palavras no excel?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=396"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/396\/revisions"}],"predecessor-version":[{"id":930,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/396\/revisions\/930"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}