{"id":495,"date":"2023-10-26T09:17:37","date_gmt":"2023-10-26T09:17:37","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/"},"modified":"2023-12-06T11:43:09","modified_gmt":"2023-12-06T11:43:09","slug":"numero-de-formato","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/","title":{"rendered":"Como usar a fun\u00e7\u00e3o vba formatnumber?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-2173730811\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-1361334863\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>A fun\u00e7\u00e3o VBA FORMATNUMBER est\u00e1 listada na categoria de convers\u00e3o de tipo de dados das fun\u00e7\u00f5es VBA. Quando voc\u00ea o usa no c\u00f3digo VBA, <strong>ele retorna a express\u00e3o fornecida aplicando um formato num\u00e9rico a ela<\/strong> . Em termos simples, o resultado obtido tem um formato num\u00e9rico como um tipo de dados string.<\/p><h2 class=\"wp-block-heading\"> Sintaxe<\/h2><p> <strong>FormatNumber(Express\u00e3o, [NumDigitsAfterDecimal], [IncludeLeadingDigit],[UseParensForNegativeNumbers], [GroupDigits])<\/strong><\/p><h2 class=\"wp-block-heading\"> Argumentos<\/h2><ul><li> <strong>Express\u00e3o<\/strong> : A express\u00e3o que voc\u00ea deseja formatar.<\/li><li> <strong>[NumDigitsAfterDecimal]<\/strong> : Um valor num\u00e9rico para especificar casas decimais [Este \u00e9 um argumento opcional e, se omitido, o padr\u00e3o \u00e9 -1].<\/li><li> <strong>[IncludeLeadingDigit]<\/strong> : um valor de enumera\u00e7\u00e3o para especificar se um zero \u00e0 esquerda deve ser exibido [Este \u00e9 um argumento opcional e, se omitido, vbUseDefault por padr\u00e3o].<ul><li> vbFalse: n\u00e3o deve ser precedido de zero.<\/li><li> vbTrue: exibe um zero \u00e0 esquerda.<\/li><li> vbUseDefault: usa configura\u00e7\u00f5es padr\u00e3o.<\/li><\/ul><\/li><li> <strong>[UseParensForNegativeNumbers]<\/strong> : um valor de enumera\u00e7\u00e3o para especificar se os n\u00fameros negativos devem ser colocados entre par\u00eanteses (este \u00e9 um argumento opcional e, se omitido, o padr\u00e3o \u00e9 vbUseDefault).<ul><li> vbFalse: para n\u00e3o colocar n\u00fameros negativos entre par\u00eanteses.<\/li><li> vbTrue: coloque n\u00fameros negativos entre par\u00eanteses.<\/li><li> vbUseDefault: usa configura\u00e7\u00f5es padr\u00e3o.<\/li><\/ul><\/li><li> <strong>[GroupDigits]<\/strong> : n valor de enumera\u00e7\u00e3o para especificar se o n\u00famero deve ser agrupado (em milhares, etc.), usando o delimitador de grupo especificado na localidade do computador [Este \u00e9 um argumento opcional e se \u00e9 omitido, vbUseDefault por padr\u00e3o].<ul><li> vbFalse: para n\u00e3o usar os n\u00fameros do grupo.<\/li><li> vbTrue: para usar os n\u00fameros do grupo.<\/li><li> vbUseDefault: Usa as configura\u00e7\u00f5es padr\u00e3o do computador.<\/li><\/ul><\/li><\/ul><h2 class=\"wp-block-heading\"> Exemplo<\/h2><p> Para entender de forma pr\u00e1tica como usar a fun\u00e7\u00e3o VBA FORMATNUMBER, voc\u00ea precisa seguir o exemplo abaixo, onde escrevemos um c\u00f3digo VBA usando-a: <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" title=\"exemplo-vba-formaton\u00famero-fun\u00e7\u00e3o\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png\" sizes=\"auto, \" srcset=\"\" alt=\"example-vba-formatnumber-function\" width=\"843\" height=\"420\"><\/figure><\/div><pre class=\"wp-block-code\"> <code class=\"language-visual-basic\" lang=\"visual-basic\">Sub example_FORMATNUMBER() Range(\"B1\").Value = FormatNumber(Range(\"A1\")) End Sub<\/code><\/pre><p> No c\u00f3digo acima, usamos FORMATNUMBER para converter o valor da c\u00e9lula A1 em um valor num\u00e9rico e retornamos o resultado na c\u00e9lula B1.<\/p><h2 class=\"wp-block-heading\"> Coment\u00e1rios<\/h2><ul><li> Se o valor especificado for diferente de um n\u00famero ou string que n\u00e3o pode ser reconhecido como um n\u00famero, o VBA retornar\u00e1 o erro de tempo de execu\u00e7\u00e3o 13. <\/li><\/ul><div class=\"wp-block-group more-tutorials is-layout-flow\"><div class=\"wp-block-group__inner-container\"><h2 class=\"wp-block-heading\"> Mais tutoriais <\/h2><div class=\"wp-block-columns is-layout-flex wp-container-260\"><div class=\"wp-block-column is-layout-flow\"><ul><li> <a href=\"https:\/\/exceladvisor.org\/pt\/bool\/\">VBA CBOOL<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/cbyte\/\">Bytes VBA<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/ocorrer\/\">CCUR do VBA<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/cdate\/\">CDATE VBA<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/cdbl\/\">CDBL VBA<\/a><\/li><\/ul><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-495","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?<\/title>\n<meta name=\"description\" content=\"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?\" \/>\n<meta property=\"og:description\" content=\"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:43:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/\",\"name\":\"\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png\",\"datePublished\":\"2023-10-26T09:17:37+00:00\",\"dateModified\":\"2023-12-06T11:43:09+00:00\",\"description\":\"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como usar a fun\u00e7\u00e3o vba formatnumber?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?","description":"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/","og_locale":"pt_PT","og_type":"article","og_title":"\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?","og_description":"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","og_url":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:43:09+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/","url":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/","name":"\u25b7 Como usar a fun\u00e7\u00e3o VBA FORMATNUMBER?","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png","datePublished":"2023-10-26T09:17:37+00:00","dateModified":"2023-12-06T11:43:09+00:00","description":"Aprenda como usar a fun\u00e7\u00e3o VBA FORMATNUMBER com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/numero-de-formato\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-formatnumber.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/numero-de-formato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como usar a fun\u00e7\u00e3o vba formatnumber?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/495\/revisions"}],"predecessor-version":[{"id":1266,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/495\/revisions\/1266"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}