{"id":501,"date":"2023-10-26T08:06:31","date_gmt":"2023-10-26T08:06:31","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/instrucao\/"},"modified":"2023-12-06T11:43:13","modified_gmt":"2023-12-06T11:43:13","slug":"instrucao","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/instrucao\/","title":{"rendered":"Como usar a fun\u00e7\u00e3o vba instr?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-136282288\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-1336335991\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>A fun\u00e7\u00e3o VBA INSTR est\u00e1 listada na categoria de texto das fun\u00e7\u00f5es VBA. Quando voc\u00ea o usa no c\u00f3digo VBA, <strong>ele retorna o n\u00famero da posi\u00e7\u00e3o inicial de uma substring (especificada por voc\u00ea) de outra string<\/strong> . Em termos simples, funciona como fun\u00e7\u00f5es <a style=\"outline: none;\" href=\"https:\/\/exceladvisor.org\/pt\/funcoes-de-string-do-excel\/\">FIND<\/a> e <a href=\"https:\/\/exceladvisor.org\/pt\/funcoes-de-string-do-excel\/\">SEARCH<\/a> (fun\u00e7\u00f5es de planilha).<\/p><h2 class=\"wp-block-heading\"> Sintaxe<\/h2><p> <strong>InStr([Iniciar], String1, String2, [Comparar])<\/strong><\/p><h2 class=\"wp-block-heading\"> Argumentos<\/h2><ul><li> <strong>[Iniciar]<\/strong> : um n\u00famero inteiro para especificar a posi\u00e7\u00e3o a partir da qual voc\u00ea deseja iniciar a pesquisa [Este \u00e9 um argumento opcional e, se omitido, o padr\u00e3o do VBA \u00e9 1].<\/li><li> <strong>String1<\/strong> : a string que voc\u00ea deseja pesquisar.<\/li><li> <strong>String2<\/strong> : A string que voc\u00ea deseja pesquisar.<\/li><li> <strong>[Compare]<\/strong> : Um valor de string para definir a compara\u00e7\u00e3o a ser executada ao filtrar o array [Este \u00e9 um argumento opcional e se omitido, o VBA usa vbBinaryCompare por padr\u00e3o].<ul><li> vbBinaryCompare: para compara\u00e7\u00e3o bin\u00e1ria.<\/li><li> vbTextCompare: para compara\u00e7\u00e3o de texto.<\/li><li> vbDatabaseCompare: para compara\u00e7\u00e3o de banco de dados.<\/li><\/ul><\/li><\/ul><h2 class=\"wp-block-heading\"> Exemplo<\/h2><p> Para entender de forma pr\u00e1tica como usar a fun\u00e7\u00e3o VBA INSTR, voc\u00ea precisa seguir o exemplo abaixo, onde escrevemos um c\u00f3digo VBA usando-a: <\/p><div class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"exemplo-vba-instr-fun\u00e7\u00e3o\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png\" sizes=\"auto, \" srcset=\"\" alt=\"example-vba-instr-function\" width=\"838\" height=\"482\"><\/div><pre class=\"wp-block-code\"> <code class=\"language-visual-basic\" lang=\"visual-basic\">Sub example_INSTR() Range(\"B1\").Value = InStr(Range(\"A1\"), \" \") End Sub<\/code><\/pre><p> No c\u00f3digo acima usamos INSTR para encontrar o espa\u00e7o no valor (Mick Griffin) na c\u00e9lula A1 e retornou 5 como resultado existe o primeiro espa\u00e7o entre &#8216;Mick&#8217; e &#8216;Griffin&#8217; cuja posi\u00e7\u00e3o \u00e9 5.<\/p><h2 class=\"wp-block-heading\"> Coment\u00e1rios<\/h2><p> Abaixo est\u00e3o alguns pontos importantes que voc\u00ea precisa considerar ao usar a fun\u00e7\u00e3o INSTR no VBA.<\/p><ul><li> Se &#8220;string1&#8221; n\u00e3o puder ser encontrado em &#8220;string2&#8221;, o resultado ser\u00e1 0. <\/li><\/ul><div class=\"wp-block-group more-tutorials is-layout-flow\"><div class=\"wp-block-group__inner-container\"><h2 class=\"wp-block-heading\"> Mais tutoriais <\/h2><div class=\"wp-block-columns is-layout-flex wp-container-240\"><div class=\"wp-block-column is-layout-flow\"><ul><li> <a href=\"https:\/\/exceladvisor.org\/pt\/strconv\/\">VBA STRCONV<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/corda\/\">CADEIA VBA<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/strerreverso\/\">VBA STRE INVERSO<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/aparar\/\">TRIM VBA<\/a><\/li><li> VBAUCASE<\/li><\/ul><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-501","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)<\/title>\n<meta name=\"description\" content=\"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/instrucao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)\" \/>\n<meta property=\"og:description\" content=\"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/instrucao\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:43:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/\",\"name\":\"Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png\",\"datePublished\":\"2023-10-26T08:06:31+00:00\",\"dateModified\":\"2023-12-06T11:43:13+00:00\",\"description\":\"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/instrucao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/instrucao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como usar a fun\u00e7\u00e3o vba instr?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)","description":"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/instrucao\/","og_locale":"pt_PT","og_type":"article","og_title":"Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)","og_description":"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","og_url":"https:\/\/exceladvisor.org\/pt\/instrucao\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:43:13+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/","url":"https:\/\/exceladvisor.org\/pt\/instrucao\/","name":"Como usar a fun\u00e7\u00e3o VBA INSTR? (Sintaxe + Exemplo)","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png","datePublished":"2023-10-26T08:06:31+00:00","dateModified":"2023-12-06T11:43:13+00:00","description":"Aprenda como usar a fun\u00e7\u00e3o VBA INSTR com sintaxe, argumentos e exemplo com c\u00f3digo de exemplo.","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/instrucao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-vba-instr.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/instrucao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como usar a fun\u00e7\u00e3o vba instr?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/501\/revisions"}],"predecessor-version":[{"id":1272,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/501\/revisions\/1272"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}