{"id":585,"date":"2023-10-22T04:31:54","date_gmt":"2023-10-22T04:31:54","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/"},"modified":"2023-12-06T11:42:00","modified_gmt":"2023-12-06T11:42:00","slug":"excluir-o-ultimo-caractere-2","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/","title":{"rendered":"Como remover o \u00faltimo caractere de uma string?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-3543264557\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-3586708129\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p>No Excel, para remover o \u00faltimo caractere de uma string em uma c\u00e9lula, voc\u00ea precisa criar uma f\u00f3rmula combinando as fun\u00e7\u00f5es LEFT e LEN. Essas fun\u00e7\u00f5es permitem remover o \u00faltimo caractere (lado direito) aparando-o ao extrair a string. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-83682\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png\" sizes=\"auto, \" srcset=\"\" alt=\"remova o \u00faltimo caractere de uma string\" width=\"688\" height=\"358\"><\/figure><\/div><p> Use as etapas abaixo para escrever esta f\u00f3rmula:<\/p><ol type=\"1\"><li> Primeiro insira a fun\u00e7\u00e3o ESQUERDA em uma c\u00e9lula, e no primeiro argumento refira-se \u00e0 c\u00e9lula que cont\u00e9m o texto original.<\/li><li> Ent\u00e3o, no segundo argumento de LEFT, insira a fun\u00e7\u00e3o LEN.<\/li><li> Depois disso, na fun\u00e7\u00e3o LEN, consulte a c\u00e9lula A2 e feche a fun\u00e7\u00e3o LEN com os par\u00eanteses de fechamento.<\/li><li> No final, menos 1 da fun\u00e7\u00e3o LEN em [num_chars] e feche a fun\u00e7\u00e3o LEFT. <\/li><\/ol><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-83684\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/2-a-gauche-et-len-pour-supprimer-le-dernier-caractere.png\" sizes=\"auto, \" srcset=\"\" alt=\"left-and-len-para-remover-o-\u00faltimo caractere\" width=\"597\" height=\"190\"><\/figure><\/div><p> Quando voc\u00ea pressiona Enter, voc\u00ea obt\u00e9m uma nova string da string original ap\u00f3s remover o \u00faltimo caractere.<\/p><pre class=\"wp-block-code\"> <code class=\"language-excel-formula\" lang=\"excel-formula\">=LEFT(A1,LEN(A1)-1)<\/code><\/pre><p> Voc\u00ea tamb\u00e9m pode usar a fun\u00e7\u00e3o TRIM para remover qualquer espa\u00e7o indesejado que tenha antes e depois da string. Nosso exemplo possui um espa\u00e7o entre os \u201cCampos\u201d e o \u201c1\u201d. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-83685\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/3-garnitures-pour-supprimer-lespace-indesirable.png\" sizes=\"auto, \" srcset=\"\" alt=\"cortar para remover espa\u00e7o de lixo\" width=\"697\" height=\"340\"><\/figure><\/div><p> E quando voc\u00ea remove o \u00faltimo caractere, o espa\u00e7o permanece com a string. Veja o instant\u00e2neo abaixo. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-83686\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/4-trim-avec-gauche-et-len.png\" sizes=\"auto, \" srcset=\"\" alt=\"cortar com esquerda e comprimento\" width=\"651\" height=\"333\"><\/figure><\/div><p> \u00c9 por isso que \u00e9 melhor usar TRIM com LEFT e LEN. <\/p><div class=\"gb-container gb-container-52dfcee1 gb-container-sample-file\"><h2 class=\"gb-headline gb-headline-e289c143 gb-headline-text gb-headline-4f7959c2\"> Obtenha o arquivo Excel<\/h2><p> <a class=\"gb-button gb-button-e88d6bee gb-button-text gb-button-button1\" href=\"https:\/\/exceladvisor.org\/pt\/a\/\" rel=\"nofollow\">Download<\/a><\/p><\/div><div class=\"gb-container gb-container-4db6181c gb-container-mt\"> <a class=\"gb-button gb-button-c5897111 gb-button-text gb-button-mt-button\" href=\"https:\/\/exceladvisor.org\/pt\/vba\/\">O que \u00e9 VBA<\/a><h2 class=\"gb-headline gb-headline-665e5f6b gb-headline-text gb-headline-mt-heading\"> Tutoriais relacionados <\/h2><div class=\"gb-grid-wrapper gb-grid-wrapper-a20baf7c gb-grid-wrapper-mt-grid\"><div class=\"gb-grid-column gb-grid-column-65ddf67e\"><div class=\"gb-container gb-container-65ddf67e\"><ul><li> Remova o primeiro caractere de uma c\u00e9lula no Excel<\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/remover-espacos-extras\/\">Remova espa\u00e7os extras no Excel<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/obter-a-primeira-ultima-palavra\/\">Nomes separados no Excel \u2013 (nome e sobrenome)<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/extrair-a-ultima-palavra-2\/\">Extraia a \u00faltima palavra de uma c\u00e9lula<\/a><\/li><li> <a href=\"https:\/\/exceladvisor.org\/pt\/remover-quebra-de-linha-2\/\">Remover quebra de linha de uma c\u00e9lula<\/a><\/li><\/ul><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-585","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como remover o \u00faltimo caractere de uma string no Excel?<\/title>\n<meta name=\"description\" content=\"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como remover o \u00faltimo caractere de uma string no Excel?\" \/>\n<meta property=\"og:description\" content=\"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/\",\"name\":\"Como remover o \u00faltimo caractere de uma string no Excel?\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png\",\"datePublished\":\"2023-10-22T04:31:54+00:00\",\"dateModified\":\"2023-12-06T11:42:00+00:00\",\"description\":\"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como remover o \u00faltimo caractere de uma string?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como remover o \u00faltimo caractere de uma string no Excel?","description":"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/","og_locale":"pt_PT","og_type":"article","og_title":"Como remover o \u00faltimo caractere de uma string no Excel?","og_description":"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026","og_url":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:42:00+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/","url":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/","name":"Como remover o \u00faltimo caractere de uma string no Excel?","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png","datePublished":"2023-10-22T04:31:54+00:00","dateModified":"2023-12-06T11:42:00+00:00","description":"Este tutorial ensinar\u00e1 como escrever uma f\u00f3rmula Excel para remover o \u00faltimo caractere de uma string. Vamos verificar isso\u2026","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/1-supprimer-le-dernier-caractere-dune-chaine.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/excluir-o-ultimo-caractere-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como remover o \u00faltimo caractere de uma string?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=585"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/585\/revisions"}],"predecessor-version":[{"id":1174,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/585\/revisions\/1174"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}