{"id":640,"date":"2023-10-15T12:42:55","date_gmt":"2023-10-15T12:42:55","guid":{"rendered":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/"},"modified":"2023-12-06T11:44:07","modified_gmt":"2023-12-06T11:44:07","slug":"funcoes-de-pesquisa-do-excel","status":"publish","type":"page","link":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/","title":{"rendered":"Como usar fun\u00e7\u00f5es de pesquisa no excel?"},"content":{"rendered":"<div class=\"excel-before-content-2\" id=\"excel-3488912674\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div><div class=\"excel-before-content\" id=\"excel-3006738631\"><script type=\"text\/javascript\">\r\n\tatOptions = {\r\n\t\t'key' : 'c1158f160081d6540a8409e6925dab94',\r\n\t\t'format' : 'iframe',\r\n\t\t'height' : 250,\r\n\t\t'width' : 300,\r\n\t\t'params' : {}\r\n\t};\r\n<\/script>\r\n<script type=\"text\/javascript\" src=\"\/\/www.highperformanceformat.com\/c1158f160081d6540a8409e6925dab94\/invoke.js\"><\/script><\/div> <p><strong><em><a href=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel_lookup_functions_sample_files.zip\">arquivos de amostra<\/a><\/em><\/strong><\/p><h2 class=\"wp-block-heading\"> 1. Fun\u00e7\u00e3o ENDERE\u00c7O<\/h2><p> <strong>A fun\u00e7\u00e3o ADDRESS retorna uma refer\u00eancia de c\u00e9lula v\u00e1lida com base no endere\u00e7o da coluna e da linha.<\/strong> Em termos simples, voc\u00ea pode criar o endere\u00e7o de uma c\u00e9lula usando o n\u00famero da linha e o n\u00famero da coluna.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> <em>ENDERE\u00c7O(n\u00fam_linha,n\u00fam_coluna,n\u00fam_abs,A1,texto_folha)<\/em><\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>row_num:<\/strong> um n\u00famero para especificar o n\u00famero da linha.<\/li><li> <strong>column_num:<\/strong> um n\u00famero para especificar o n\u00famero da coluna.<\/li><li> <strong>[abs_num]:<\/strong> Tipo de refer\u00eancia.<\/li><li> <strong>[A1]:<\/strong> estilo de refer\u00eancia.<\/li><li> <strong>[sheet_text]:<\/strong> um valor de texto como o nome da planilha.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Por padr\u00e3o, a fun\u00e7\u00e3o ADDRESS retorna uma refer\u00eancia absoluta no resultado.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos argumentos diferentes para obter todos os tipos de resultados. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36829\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-endere\u00e7o-fun\u00e7\u00e3o-exemplo-1\" width=\"744\" height=\"452\"><\/figure><\/div><p> <strong>Com<\/strong> <a href=\"https:\/\/exceladvisor.org\/pt\/r1c1\/\"><strong>estilo de refer\u00eancia R1C1<\/strong><\/a> <strong>:<\/strong><\/p><ul><li> Refer\u00eancia relativa.<\/li><li> Refer\u00eancia relativa de linha e refer\u00eancia absoluta de coluna.<\/li><li> Refer\u00eancia absoluta de linha e coluna relativa.<\/li><li> Refer\u00eancia absoluta.<\/li><\/ul><p> <strong>Com estilo de refer\u00eancia A1:<\/strong><\/p><ul><li> Refer\u00eancia relativa.<\/li><li> Refer\u00eancia relativa de linha e refer\u00eancia absoluta de coluna.<\/li><li> Refer\u00eancia absoluta de linha e coluna relativa.<\/li><li> Refer\u00eancia absoluta.<\/li><\/ul><h2 class=\"wp-block-heading\"> 2. Fun\u00e7\u00e3o ZONAS<\/h2><p> <strong>A fun\u00e7\u00e3o AREAS retorna um n\u00famero que representa o n\u00famero de intervalos na refer\u00eancia que voc\u00ea especificou.<\/strong> Em termos simples, na verdade conta as diferentes \u00e1reas da planilha que voc\u00ea referenciou na fun\u00e7\u00e3o.<\/p><h3 class=\"wp-block-heading\"> <strong>sintaxe<\/strong><\/h3><p> CAMPOS (refer\u00eancia)<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>refer\u00eancia:<\/strong> uma refer\u00eancia a uma c\u00e9lula ou intervalo de c\u00e9lulas.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> A refer\u00eancia pode ser uma c\u00e9lula, um intervalo de c\u00e9lulas ou um intervalo nomeado.<\/li><li> Se quiser fazer refer\u00eancia a v\u00e1rias refer\u00eancias de c\u00e9lulas, voc\u00ea dever\u00e1 colocar todas essas refer\u00eancias entre v\u00e1rios conjuntos de par\u00eanteses e usar v\u00edrgulas para separar cada refer\u00eancia das outras.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos a fun\u00e7\u00e3o zones para obter a refer\u00eancia num\u00e9rica em um intervalo nomeado. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36857\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/zones-excel-exemple-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"Excel-Zonas-Exemplo-1\" width=\"572\" height=\"365\"><\/figure><\/div><p> Como voc\u00ea pode ver, existem tr\u00eas colunas no intervalo e retornou 3 no resultado. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36858\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-zone-excel-2-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-Zona-fun\u00e7\u00e3o-exemplo-2 (1)\" width=\"580\" height=\"380\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 3. ESCOLHA a fun\u00e7\u00e3o<\/h2><p> <strong>A fun\u00e7\u00e3o SELECT retorna um valor da lista de valores com base no n\u00famero da posi\u00e7\u00e3o especificada.<\/strong> Em termos simples, procura um valor numa lista com base na sua posi\u00e7\u00e3o e devolve-o no resultado.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> <em>SELECIONE(num_\u00edndice,valor1,valor2,\u2026)<\/em><\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>index_num:<\/strong> n\u00famero usado para especificar a posi\u00e7\u00e3o do valor na lista.<\/li><li> <strong>valor1:<\/strong> um intervalo de c\u00e9lulas ou valor de entrada que voc\u00ea pode escolher.<\/li><li> <strong>[valor2]:<\/strong> um intervalo de c\u00e9lulas ou valor de entrada que voc\u00ea pode escolher.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea pode fazer refer\u00eancia a uma c\u00e9lula ou tamb\u00e9m inserir valores diretamente na fun\u00e7\u00e3o.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos a fun\u00e7\u00e3o CHOOSE com uma lista suspensa para calcular quatro coisas diferentes (soma, m\u00e9dia, m\u00e1ximo e mix). Ent\u00e3o usamos a f\u00f3rmula abaixo para calcular as quatro coisas:<\/p><p> =ESCOLHER(PROCV(K2,Q1:R4,2,FALSO),SOMA(O2:O9),M\u00c9DIA(O2:O9),M\u00c1X(O2:O9),MIN(O2:O9)) <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36875\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-choisir-la-fonction-exemple-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-escolha-fun\u00e7\u00e3o-exemplo-1\" width=\"764\" height=\"448\"><\/figure><\/div><p> Temos esta tabelinha com os nomes dos quatro c\u00e1lculos que queremos e um n\u00famero de s\u00e9rie para cada um na c\u00e9lula correspondente.<\/p><p> Depois disso, temos uma lista suspensa para todos os quatro c\u00e1lculos. Agora, para obter o n\u00famero de \u00edndice na fun\u00e7\u00e3o de escolha desta pequena tabela, temos uma f\u00f3rmula de pesquisa que retornar\u00e1 o n\u00famero de s\u00e9rie de acordo com o valor selecionado na lista suspensa.<\/p><p> E em vez de valores, usamos quatro f\u00f3rmulas para 4 c\u00e1lculos diferentes.<\/p><h2 class=\"wp-block-heading\"> 4. Fun\u00e7\u00e3o COLUNA<\/h2><p> <strong>A fun\u00e7\u00e3o COLUMN retorna o n\u00famero da coluna para a refer\u00eancia de c\u00e9lula fornecida.<\/strong> Como voc\u00ea sabe, cada refer\u00eancia de c\u00e9lula consiste em um n\u00famero de coluna e um n\u00famero de linha. Ent\u00e3o ele pega o n\u00famero da coluna e o retorna no resultado.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> COLUNA([refer\u00eancia])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>refer\u00eancia:<\/strong> uma refer\u00eancia de c\u00e9lula para a qual voc\u00ea deseja obter o n\u00famero da coluna.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea n\u00e3o pode fazer refer\u00eancia a m\u00faltiplas refer\u00eancias.<\/li><li> Se voc\u00ea estiver se referindo a um array, a fun\u00e7\u00e3o de coluna tamb\u00e9m retornar\u00e1 os n\u00fameros das colunas em um array.<\/li><li> Se voc\u00ea estiver se referindo a um intervalo de m\u00faltiplas c\u00e9lulas, ele retornar\u00e1 o n\u00famero da coluna da c\u00e9lula mais \u00e0 esquerda. Por exemplo, se voc\u00ea se referir ao intervalo A1:C10, ele retornar\u00e1 o n\u00famero da coluna da c\u00e9lula A1.<\/li><li> Se voc\u00ea pular a especifica\u00e7\u00e3o de uma refer\u00eancia, ele retornar\u00e1 o n\u00famero da coluna da c\u00e9lula atual.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos COLUMN para obter o n\u00famero da coluna da c\u00e9lula A1. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36878\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-colonne-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"Excel-coluna-fun\u00e7\u00e3o-exemplo-1\" width=\"516\" height=\"307\"><\/figure><\/div><p> Como j\u00e1 mencionei, se voc\u00ea ignorar a refer\u00eancia da c\u00e9lula, o n\u00famero da coluna da c\u00e9lula atual ser\u00e1 retornado. No exemplo abaixo, usamos COLUMN para criar um cabe\u00e7alho com n\u00fameros de s\u00e9rie. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36879\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-colonne-excel-2.png\" sizes=\"auto, \" srcset=\"\" alt=\"Excel-coluna-fun\u00e7\u00e3o-exemplo-2\" width=\"548\" height=\"312\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 5. Fun\u00e7\u00e3o COLUNAS<\/h2><p> <strong>A fun\u00e7\u00e3o COLUMNS retorna o n\u00famero de colunas referenciadas na refer\u00eancia fornecida.<\/strong> Em termos simples, conta o n\u00famero de colunas no intervalo fornecido e retorna esse n\u00famero.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> COLUNAS(tabela)<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>tabela:<\/strong> uma tabela ou intervalo de c\u00e9lulas do qual voc\u00ea deseja obter o n\u00famero de colunas.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea tamb\u00e9m pode usar um intervalo nomeado.<\/li><li> A fun\u00e7\u00e3o COLUMNS n\u00e3o se preocupa com valores nas c\u00e9lulas, ela simplesmente retornar\u00e1 o n\u00famero de colunas de uma refer\u00eancia.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos COLUMN para obter o n\u00famero de colunas no intervalo A1:F1. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36881\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Exemple-de-fonction-de-colonnes-Excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"Excel-colunas-fun\u00e7\u00e3o-exemplo-1\" width=\"529\" height=\"396\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 6. Fun\u00e7\u00e3o FORMULATEXT<\/h2><p> <strong>A fun\u00e7\u00e3o FORMULATEXT retorna a f\u00f3rmula da c\u00e9lula referenciada.<\/strong> E se n\u00e3o houver nenhuma f\u00f3rmula na c\u00e9lula referenciada, um valor ou um espa\u00e7o em branco, ele retornar\u00e1 um #N\/A.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> TEXTFORMULA (refer\u00eancia)<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>refer\u00eancia:<\/strong> a refer\u00eancia da c\u00e9lula da qual voc\u00ea deseja obter a f\u00f3rmula como texto.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Se voc\u00ea estiver fazendo refer\u00eancia a outra pasta de trabalho, essa pasta de trabalho dever\u00e1 estar aberta, caso contr\u00e1rio, n\u00e3o exibir\u00e1 a f\u00f3rmula.<\/li><li> Se voc\u00ea estiver se referindo a um intervalo com mais de uma c\u00e9lula, ele retornar\u00e1 a f\u00f3rmula para a c\u00e9lula superior esquerda do intervalo fornecido.<\/li><li> Ele retornar\u00e1 um valor de erro &#8220;#N\/A&#8221; se a c\u00e9lula que voc\u00ea est\u00e1 usando como refer\u00eancia n\u00e3o contiver nenhuma f\u00f3rmula, tiver uma f\u00f3rmula com mais de 8.192 caracteres, uma c\u00e9lula estiver protegida ou uma pasta de trabalho externa n\u00e3o estiver aberta.<\/li><li> Se voc\u00ea fizer refer\u00eancia a duas c\u00e9lulas em uma refer\u00eancia circular, os resultados de ambas ser\u00e3o retornados.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos texto de f\u00f3rmula com diferentes tipos de refer\u00eancia. Quando voc\u00ea se refere a uma c\u00e9lula que n\u00e3o possui f\u00f3rmula, ela retornar\u00e1 o valor de erro &#8220;#N\/A&#8221;. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36924\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-texte-de-formule-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"Excel-f\u00f3rmulatexto-fun\u00e7\u00e3o-exemplo-1\" width=\"439\" height=\"290\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 7. Fun\u00e7\u00e3o HSEARCH<\/h2><p> <strong>A fun\u00e7\u00e3o HLOOKUP procura um valor na linha superior de uma tabela e retorna o valor na mesma coluna do valor correspondente usando o n\u00famero de \u00edndice.<\/strong> Em termos simples, ele pesquisa horizontalmente.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> PROCH(valor_procurado, matriz_tabela, n\u00fam_\u00edndice_linha, [procura_intervalo])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>lookup_value:<\/strong> o valor que voc\u00ea deseja procurar.<\/li><li> <strong>table_array:<\/strong> a tabela de dados ou matriz da qual voc\u00ea deseja encontrar o valor.<\/li><li> <strong>row_index_num:<\/strong> um valor num\u00e9rico que representa um n\u00famero de linhas abaixo da linha superior da qual voc\u00ea deseja obter o valor. Por exemplo, se voc\u00ea especificar 2 e seu valor de pesquisa estiver em A10 na tabela de dados, ele retornar\u00e1 o valor na c\u00e9lula B10.<\/li><li> <strong>[range_lookup]:<\/strong> um valor l\u00f3gico para especificar o tipo de pesquisa. Se voc\u00ea quiser fazer uma pesquisa de correspond\u00eancia exata, use FALSE e se quiser fazer uma pesquisa de correspond\u00eancia n\u00e3o exata, use TRUE (padr\u00e3o).<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea pode usar curingas.<\/li><li> Voc\u00ea pode fazer correspond\u00eancia exata e correspond\u00eancia difusa.<\/li><li> Ao realizar uma correspond\u00eancia difusa, certifique-se de classificar os dados em ordem crescente da esquerda para a direita e, se os dados n\u00e3o estiverem em ordem crescente, um resultado impreciso ser\u00e1 retornado.<\/li><li> Se range_lookup for verdadeiro ou omitido, ele executar\u00e1 uma correspond\u00eancia n\u00e3o exata, mas retornar\u00e1 uma correspond\u00eancia exata se o valor de pesquisa existir no intervalo de pesquisa.<\/li><li> Se range_lookup for verdadeiro ou omitido e o valor de pesquisa n\u00e3o estiver no intervalo de pesquisa, ele retornar\u00e1 o valor mais pr\u00f3ximo que for menor que o valor de pesquisa.<\/li><li> Se range_lookup for falso, n\u00e3o h\u00e1 necessidade de classificar o intervalo de dados.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos a fun\u00e7\u00e3o HLOOKUP com MATCH para criar uma f\u00f3rmula din\u00e2mica e, em seguida, usamos uma lista suspensa para alterar o valor de pesquisa da c\u00e9lula. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36930\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-excel-hlookup-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-hlookup-fun\u00e7\u00e3o-exemplo-1\" width=\"407\" height=\"375\"><\/figure><\/div><p> O nome do campo da c\u00e9lula C7 \u00e9 usado como valor de pesquisa. Intervalo B1: F5 como array de tabela e para row_index_num usamos a fun\u00e7\u00e3o match para obter o n\u00famero da linha. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36931\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/Excel-fonction-hlookup-exemple-2.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-hlookup-fun\u00e7\u00e3o-exemplo-2\" width=\"460\" height=\"353\"><\/figure><\/div><p> Sempre que voc\u00ea alterar o valor na c\u00e9lula C9, ele retornar\u00e1 o n\u00famero da linha da tabela. Voc\u00ea n\u00e3o precisa mudar sua f\u00f3rmula repetidamente. Basta alterar os valores no menu suspenso e voc\u00ea obter\u00e1 um valor para isso.<\/p><h2 class=\"wp-block-heading\"> 8. Fun\u00e7\u00e3o HIPERLINK<\/h2><p> <strong>A fun\u00e7\u00e3o HYPERLINK retorna uma string com um hiperlink anexado a ela.<\/strong> Em palavras simples, como a op\u00e7\u00e3o HYPERLINK que voc\u00ea tem no Excel, a fun\u00e7\u00e3o HYPERLINK ajuda a criar um hiperlink.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> HYPERLINK(link_location,[nome_amig\u00e1vel])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>Link_Location:<\/strong> o local ao qual voc\u00ea deseja adicionar um HYPERLINK. Pode ainda ser dividido em dois termos.<ol><li> <strong>link:<\/strong> pode ser o endere\u00e7o de uma c\u00e9lula ou intervalo de c\u00e9lulas na mesma planilha ou em qualquer outra planilha ou pasta de trabalho. Tamb\u00e9m podemos vincular um marcador de um documento do Word.<\/li><li> <strong>localiza\u00e7\u00e3o:<\/strong> pode ser um link para um disco r\u00edgido, um servidor usando o caminho UNC ou qualquer URL da Internet ou intranet. (No Excel online, voc\u00ea s\u00f3 pode usar o endere\u00e7o da web para a fun\u00e7\u00e3o HYPERLINK). Voc\u00ea pode inserir um link para a fun\u00e7\u00e3o inserindo-o como texto entre aspas ou referenciando uma c\u00e9lula que cont\u00e9m o link como texto. Certifique-se de usar \u201cHTTPS: \/\/\u201d antes de um endere\u00e7o da web.<\/li><\/ol><\/li><li> <strong>[friendly_name]:<\/strong> Esta \u00e9 uma parte opcional deste recurso. Ele atua como a face do link de conex\u00e3o.<ol><li> Voc\u00ea pode usar qualquer tipo de texto, n\u00famero ou ambos.<\/li><li> Voc\u00ea tamb\u00e9m est\u00e1 se referindo a uma c\u00e9lula que cont\u00e9m o nome amig\u00e1vel.<\/li><li> Se voc\u00ea ignor\u00e1-lo, a fun\u00e7\u00e3o usar\u00e1 o endere\u00e7o do link para exibir.<\/li><li> Se friendly_name retornar um erro, a fun\u00e7\u00e3o exibir\u00e1 um erro.<\/li><\/ol><\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> <strong>Vincular um arquivo salvo a um endere\u00e7o da web:<\/strong> voc\u00ea pode usar um arquivo salvo em um endere\u00e7o da web. Isso nos ajuda a compartilhar o arquivo com efici\u00eancia.<\/li><li> <strong>Vincular um arquivo salvo em um disco r\u00edgido:<\/strong> Voc\u00ea tamb\u00e9m pode usar esta fun\u00e7\u00e3o ao trabalhar offline. Voc\u00ea pode vincular um arquivo armazenado em seu disco r\u00edgido e acess\u00e1-lo por meio de uma \u00fanica planilha do Excel, sem necessidade de ir a cada pasta para abri-los.<\/li><li> <strong>Vincular arquivo de documento do Word:<\/strong> Este tamb\u00e9m \u00e9 um recurso incr\u00edvel do recurso HYPERLINK. Voc\u00ea pode vincular um arquivo de documento do Word ou um local espec\u00edfico em um arquivo de documento do Word usando um marcador.<\/li><li> <strong>Vincular um arquivo sem usar um nome amig\u00e1vel:<\/strong> se desejar exibir o link real para o arquivo ou local para o usu\u00e1rio. Nesta situa\u00e7\u00e3o, basta ignorar a declara\u00e7\u00e3o de nome amig\u00e1vel na fun\u00e7\u00e3o HYPERLINK.<\/li><\/ul><h2 class=\"wp-block-heading\"> 9. Fun\u00e7\u00e3o INDIRETA<\/h2><p> <strong>A fun\u00e7\u00e3o INDIRETO retorna uma refer\u00eancia v\u00e1lida de uma sequ\u00eancia de texto que representa uma refer\u00eancia de c\u00e9lula.<\/strong> Em termos simples, voc\u00ea pode se referir a um intervalo de c\u00e9lulas usando o endere\u00e7o da c\u00e9lula como valor de texto.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> INDIRETO(texto_ref, [a1])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>ref_text:<\/strong> texto que representa o endere\u00e7o de uma c\u00e9lula, o endere\u00e7o de um intervalo de c\u00e9lulas, um intervalo nomeado ou o nome de uma tabela. Por exemplo, A1, B10:B20 ou MyRange.<\/li><li> <strong>[a1]:<\/strong> Um n\u00famero ou valor booleano para representar o tipo de refer\u00eancia de c\u00e9lula especificado em ref_text. <strong>Por exemplo,<\/strong> se quiser usar o estilo de refer\u00eancia A1, use TRUE ou 1, e se quiser usar o estilo de refer\u00eancia R1C1, use FALSE ou 0 para o estilo de refer\u00eancia R1C. E se voc\u00ea n\u00e3o especificar o tipo de refer\u00eancia da c\u00e9lula, ele usar\u00e1 o estilo A1 por padr\u00e3o.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Quando voc\u00ea tiver referenciado outra pasta de trabalho, essa pasta de trabalho dever\u00e1 ser aberta.<\/li><li> Se voc\u00ea inserir uma linha ou coluna no intervalo referenciado, o INDIRETO n\u00e3o atualizar\u00e1 essa refer\u00eancia.<\/li><li> Se quiser inserir texto diretamente na fun\u00e7\u00e3o, voc\u00ea deve coloc\u00e1-lo entre aspas duplas ou tamb\u00e9m pode referenciar uma c\u00e9lula que cont\u00e9m o texto que deseja usar como refer\u00eancia.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><h4 class=\"wp-block-heading\"> <strong>1. Refer\u00eancia a outra planilha<\/strong><\/h4><p> Voc\u00ea tamb\u00e9m pode consultar outra planilha usando INDIRETO e precisa inserir o nome da planilha l\u00e1. No exemplo abaixo, usamos a fun\u00e7\u00e3o indireta para referenciar outra planilha e ter o nome da planilha na c\u00e9lula A2 e a refer\u00eancia da c\u00e9lula na c\u00e9lula B2. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37064\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-fonction-indirecte-exemple-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-fun\u00e7\u00e3o-indireta-exemplo-1\" width=\"499\" height=\"238\"><\/figure><\/div><p> Na c\u00e9lula C2, usamos a seguinte f\u00f3rmula para combinar o texto.<\/p><p> =INDIRETO(\u201c\u2019\u201d&amp;A2&amp;\u201d\u2019!\u201d&amp;B2)<\/p><p> Essa combina\u00e7\u00e3o cria um texto que \u00e9 usado pela fun\u00e7\u00e3o INDIRETO para se referir \u00e0 c\u00e9lula A1 da planilha1 e o melhor \u00e9 que quando voc\u00ea altera o nome da planilha ou o endere\u00e7o da c\u00e9lula, a refer\u00eancia muda automaticamente.<\/p><p> A c\u00e9lula A1 da \u201cPlanilha1\u201d possui o valor \u201cSim\u201d e por isso o indireto retorna o valor \u201cSim\u201d.<\/p><h4 class=\"wp-block-heading\"> <strong>2. Refer\u00eancia a outra pasta de trabalho<\/strong><\/h4><p> Voc\u00ea tamb\u00e9m pode consultar outra pasta de trabalho, da mesma forma que fizemos para outra planilha. Tudo o que voc\u00ea precisa fazer \u00e9 simplesmente adicionar um nome de pasta de trabalho em seu texto para usar como refer\u00eancia. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37065\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-indirecte-excel-2.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-fun\u00e7\u00e3o-indireta-exemplo-2\" width=\"574\" height=\"350\"><\/figure><\/div><p> No exemplo acima, usamos a seguinte f\u00f3rmula para obter o valor da c\u00e9lula A1 da pasta de trabalho \u201cLivro1\u201d.<\/p><p> =INDIRETO(\u201c[\u201c&amp;A2&amp;\u201d]\u201d&amp;B2&amp;\u201d!\u201d&amp;C2)<\/p><p> Como temos o nome da pasta de trabalho na c\u00e9lula \u201cA2\u201d, o nome da planilha na c\u00e9lula \u201cB2\u201d e o nome da c\u00e9lula na c\u00e9lula \u201cC2\u201d. N\u00f3s os combinamos para usar como texto de entrada em uma fun\u00e7\u00e3o indireta.<\/p><p class=\"qt-tip\"> <strong>Nota:<\/strong> Ao combinar uma refer\u00eancia de c\u00e9lula como texto, certifique-se de seguir a estrutura de refer\u00eancia correta.<\/p><h4 class=\"wp-block-heading\"> <strong>3. Usando intervalos nomeados<\/strong><\/h4><p> Sim, voc\u00ea tamb\u00e9m pode consultar um intervalo nomeado usando a fun\u00e7\u00e3o indireta. \u00c9 simples. Depois de criar um intervalo nomeado, voc\u00ea dever\u00e1 inseri-lo como texto em INDIRETO. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37066\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-fonction-indirecte-exemple-3.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-fun\u00e7\u00e3o-indireta-exemplo-3\" width=\"583\" height=\"257\"><\/figure><\/div><p> No exemplo acima, temos uma lista suspensa na c\u00e9lula E1 que cont\u00e9m uma lista de intervalos nomeados, e na c\u00e9lula E2 usamos esse nome. Como o intervalo B2:B5 \u00e9 denominado \u201cQuantidade\u201d e o intervalo C2:C5 \u00e9 denominado \u201cQuantidade\u201d.<\/p><p> Quando voc\u00ea seleciona uma quantidade na lista suspensa, a fun\u00e7\u00e3o indireta faz refer\u00eancia instantaneamente ao intervalo nomeado. E ao selecionar o valor no menu suspenso, voc\u00ea ter\u00e1 a soma do intervalo de c\u00e9lulas C2:C5.<\/p><h2 class=\"wp-block-heading\"> 11. Fun\u00e7\u00e3o PESQUISA<\/h2><p> <strong>A fun\u00e7\u00e3o SEARCH retorna um valor (que voc\u00ea est\u00e1 procurando) de uma linha, coluna ou tabela<\/strong> . Em termos simples, voc\u00ea pode pesquisar um valor e SEARCH retornar\u00e1 esse valor se estiver naquela linha, coluna ou tabela.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> PESQUISA(valor, intervalo_pesquisa, [intervalo_resultado])<\/p><p> Existem dois tipos de fun\u00e7\u00f5es SEARCH.<\/p><ul><li> forma vetorial<\/li><li> Formul\u00e1rio de tabela<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>valor:<\/strong> o valor que voc\u00ea deseja pesquisar em uma coluna ou linha.<\/li><li> <strong>lookup_range:<\/strong> a coluna ou linha na qual voc\u00ea deseja pesquisar o valor.<\/li><li> <strong>[result_range]:<\/strong> a coluna ou linha da qual voc\u00ea deseja retornar um valor. Este \u00e9 um argumento opcional.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Em vez de usar o formato de array, \u00e9 melhor usar VLOOKUP ou HLOOKUP.<\/li><\/ul><h2 class=\"wp-block-heading\"> 12. Fun\u00e7\u00e3o MATCH<\/h2><p> <strong>A fun\u00e7\u00e3o MATCH retorna o n\u00famero do \u00edndice de um valor de array.<\/strong> Em termos simples, a fun\u00e7\u00e3o MATCH procura um valor na lista e retorna o n\u00famero da posi\u00e7\u00e3o desse valor na lista.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> MATCH (valor_procurado, array_procurado, [tipo_correspond\u00eancia])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>lookup_value<\/strong> : o valor cuja posi\u00e7\u00e3o voc\u00ea deseja obter em uma lista de valores.<\/li><li> <strong>lookup_array<\/strong> : intervalo de c\u00e9lulas ou matriz cont\u00e9m valores.<\/li><li> <strong>[match_type]<\/strong> : o n\u00famero (-1, 0 e 1) para especificar como o Excel pesquisa o valor na lista de valores.<ol><li> Se voc\u00ea usar 1, retornar\u00e1 o maior valor igual ou menor que o valor pesquisado. Os valores da lista devem ser ordenados em ordem crescente.<\/li><li> Se voc\u00ea usar -1, retornar\u00e1 o menor valor igual ou maior que o valor pesquisado. Os valores da lista devem ser ordenados em ordem crescente.<\/li><li> Se voc\u00ea usar 0, retornar\u00e1 a correspond\u00eancia exata da lista.<\/li><\/ol><\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea pode usar <a href=\"https:\/\/exceladvisor.org\/pt\/curingas-2\/\" data-wpil=\"url\">curingas<\/a> .<\/li><li> Se n\u00e3o houver nenhum valor correspondente na lista, retornar\u00e1 #N\/A.<\/li><li> A fun\u00e7\u00e3o de correspond\u00eancia n\u00e3o diferencia mai\u00fasculas de min\u00fasculas.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos 1 como tipo de correspond\u00eancia e procuramos o valor 5. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37128\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-correspondance-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-match-function-exemplo-1\" width=\"401\" height=\"466\"><\/figure><\/div><p> Como j\u00e1 mencionei, se voc\u00ea usar 1 no tipo de correspond\u00eancia, ele retornar\u00e1 o maior valor igual ou menor que o valor da pesquisa. Em toda a lista existem 3 valores menores que 5 e 4 \u00e9 o mais alto.<\/p><p> Por isso no resultado retornou 3 que \u00e9 a posi\u00e7\u00e3o do valor 4.<\/p><h2 class=\"wp-block-heading\"> 13. Fun\u00e7\u00e3o de mudan\u00e7a<\/h2><p> <strong>A fun\u00e7\u00e3o OFFSET retorna uma refer\u00eancia a um intervalo que est\u00e1 a um n\u00famero espec\u00edfico de linhas e colunas de uma c\u00e9lula ou intervalo de c\u00e9lulas.<\/strong> Em termos simples, voc\u00ea pode se referir a uma c\u00e9lula ou intervalo de c\u00e9lulas usando linhas e colunas come\u00e7ando em uma c\u00e9lula inicial.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> OFFSET(refer\u00eancia, linhas, colunas, [altura], [largura])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>refer\u00eancia<\/strong> : a refer\u00eancia a partir da qual voc\u00ea deseja iniciar o deslocamento. Pode ser uma c\u00e9lula ou um intervalo de c\u00e9lulas adjacentes.<\/li><li> <strong>linhas<\/strong> : o n\u00famero de linhas que informam ao OFFSET para subir ou descer da refer\u00eancia. Para descer voc\u00ea precisa de um n\u00famero positivo e para subir voc\u00ea precisa de um n\u00famero negativo.<\/li><li> <strong>cols<\/strong> : O n\u00famero de colunas diz ao OFFSET para se mover para a esquerda ou para a direita da refer\u00eancia. Para ir para a direita voc\u00ea precisa de um n\u00famero positivo e para ir para a esquerda voc\u00ea precisa de um n\u00famero negativo.<\/li><li> <strong>[height]<\/strong> : um n\u00famero para especificar quais linhas incluir na refer\u00eancia.<\/li><li> <strong>[largura]:<\/strong> Um n\u00famero para especificar quais colunas incluir na refer\u00eancia.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> OFFSET \u00e9 uma fun\u00e7\u00e3o \u201cvol\u00e1til\u201d, ela recalcula toda vez que h\u00e1 uma altera\u00e7\u00e3o em uma planilha.<\/li><li> Ele exibe o #REF! valor de erro se o deslocamento estiver fora da borda da planilha.<\/li><li> Se a altura ou a largura forem omitidas, a altura e a largura de refer\u00eancia ser\u00e3o usadas.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos SUM com OFFSET para criar um intervalo din\u00e2mico que soma os valores de todos os meses de um determinado produto. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37223\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-decalage-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-offset-fun\u00e7\u00e3o-exemplo-1\" width=\"676\" height=\"364\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 14. Fun\u00e7\u00e3o LINHA<\/h2><p> <strong>A fun\u00e7\u00e3o ROW retorna o n\u00famero da linha da c\u00e9lula referenciada.<\/strong> Em palavras simples, com a fun\u00e7\u00e3o ROW voc\u00ea pode obter o n\u00famero da linha de uma c\u00e9lula e se n\u00e3o estiver se referindo a nenhuma c\u00e9lula, ela retorna o n\u00famero da linha da c\u00e9lula onde voc\u00ea a inseriu.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> LINHA([refer\u00eancia])<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>refer\u00eancia:<\/strong> uma refer\u00eancia de c\u00e9lula ou intervalo de c\u00e9lulas cujo n\u00famero de linha voc\u00ea deseja verificar.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Incluir\u00e1 todos os tipos de planilhas (folha de gr\u00e1fico, planilha ou planilha de macro).<\/li><li> Voc\u00ea pode consultar f\u00f3lios mesmo que estejam vis\u00edveis, ocultos ou muito ocultos.<\/li><li> Se voc\u00ea n\u00e3o especificar nenhum valor na fun\u00e7\u00e3o, voc\u00ea receber\u00e1 o n\u00famero da planilha na qual aplicou a fun\u00e7\u00e3o.<\/li><li> Se voc\u00ea especificar um nome de planilha inv\u00e1lido, ele retornar\u00e1 #N\/A.<\/li><li> Se voc\u00ea especificar uma refer\u00eancia de planilha inv\u00e1lida, um #REF! ser\u00e1 retornado.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, usamos a fun\u00e7\u00e3o de linha para verificar o n\u00famero da linha da mesma c\u00e9lula onde usamos a fun\u00e7\u00e3o. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37258\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-ligne-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-line-fun\u00e7\u00e3o-exemplo-1\" width=\"424\" height=\"296\"><\/figure><\/div><p> No exemplo abaixo, referenciamos outra c\u00e9lula para obter o n\u00famero da linha dessa c\u00e9lula. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37259\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-ligne-excel-2.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-line-fun\u00e7\u00e3o-exemplo-2\" width=\"430\" height=\"283\"><\/figure><\/div><p> Voc\u00ea pode usar a fun\u00e7\u00e3o de linha para criar uma lista de n\u00fameros de s\u00e9rie em sua planilha. Tudo o que voc\u00ea precisa fazer \u00e9 simplesmente inserir fun\u00e7\u00f5es de linha em uma c\u00e9lula e arrast\u00e1-la para a c\u00e9lula onde deseja adicionar os n\u00fameros de s\u00e9rie. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37260\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-ligne-excel-3.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-line-fun\u00e7\u00e3o-exemplo-3\" width=\"341\" height=\"534\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 15. Fun\u00e7\u00e3o LINHAS<\/h2><p> <strong>A fun\u00e7\u00e3o ROWS retorna o n\u00famero de linhas no intervalo referenciado.<\/strong> Em palavras simples, com a fun\u00e7\u00e3o ROWS, voc\u00ea pode contar o n\u00famero de linhas no intervalo ao qual se referiu.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> LINHAS (tabela)<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>array:<\/strong> uma refer\u00eancia de c\u00e9lula ou array para verificar o n\u00famero de linhas.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea tamb\u00e9m pode usar um intervalo nomeado.<\/li><li> N\u00e3o se preocupa com valores nas c\u00e9lulas, simplesmente retornar\u00e1 o n\u00famero de linhas de uma refer\u00eancia.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> No exemplo abaixo, referenciamos um intervalo vertical de 10 c\u00e9lulas e retornou 10 no resultado porque o intervalo possui 10 linhas. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39428\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-lignes-excel.png\" sizes=\"auto, \" srcset=\"\" alt=\"exemplo de fun\u00e7\u00e3o de linhas do Excel\" width=\"510\" height=\"448\"><\/figure><\/div><h2 class=\"wp-block-heading\"> 16. Fun\u00e7\u00e3o TRANSPOR<\/h2><p id=\"content-box-grey\"> <strong>A fun\u00e7\u00e3o TRANSPOSE altera a orienta\u00e7\u00e3o de um intervalo.<\/strong> Em palavras simples, usando esta fun\u00e7\u00e3o voc\u00ea pode alterar os dados de uma linha para uma coluna e de uma coluna para uma linha.<\/p><h3 class=\"wp-block-heading\"> <strong>Sintaxe<\/strong><\/h3><p> TRANSPOR (tabela)<\/p><h3 class=\"wp-block-heading\"> <strong>Argumentos<\/strong><\/h3><ul><li> <strong>array:<\/strong> um array ou intervalo que voc\u00ea deseja transpor.<\/li><\/ul><h3 class=\"wp-block-heading\"> <strong>Coment\u00e1rios<\/strong><\/h3><ul><li> Voc\u00ea precisa aplicar TRANSPOSE como uma fun\u00e7\u00e3o de array, usando o mesmo n\u00famero de c\u00e9lulas que possui em seu intervalo de origem pressionando Ctrl+Shift+Enter.<\/li><li> Se voc\u00ea selecionar c\u00e9lulas menores que o intervalo de origem, os dados ser\u00e3o transpostos apenas para essas c\u00e9lulas.<\/li><\/ul><h3 class=\"wp-block-heading\"> Exemplo<\/h3><p> Aqui precisamos transpor os dados do intervalo B2:D4 para o intervalo G2 a I4: <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37352\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-de-transposition-excel-1.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-transpor-fun\u00e7\u00e3o-exemplo-1\" width=\"555\" height=\"268\"><\/figure><\/div><p> Para isso, primeiro precisamos ir at\u00e9 a c\u00e9lula G2 e selecionar o intervalo de c\u00e9lulas at\u00e9 I4. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37353\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-fonction-de-transposition-exemple-2.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-transpor-fun\u00e7\u00e3o-exemplo-2\" width=\"565\" height=\"288\"><\/figure><\/div><p> Em seguida, insira (=TRANSPOSE(B2:D4)) na c\u00e9lula G2 e pressione Ctrl+Shift+Enter. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37354\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-fonction-de-transposition-exemple-3.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-transpor-fun\u00e7\u00e3o-exemplo-3\" width=\"577\" height=\"282\"><\/figure><\/div><p> TRANSPOSE converter\u00e1 dados de linhas em colunas, e a f\u00f3rmula que aplicamos \u00e9 uma f\u00f3rmula de matriz, voc\u00ea n\u00e3o pode alterar uma \u00fanica c\u00e9lula dela. <\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37355\" src=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/excel-fonction-de-transposition-exemple-4.png\" sizes=\"auto, \" srcset=\"\" alt=\"excel-transpor-fun\u00e7\u00e3o-exemplo-4\" width=\"568\" height=\"270\"><\/figure><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ub_ctt_via":"","footnotes":""},"class_list":["post-640","page","type-page","status-publish","hentry"],"featured_image_src":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como usar fun\u00e7\u00f5es de pesquisa no Excel?<\/title>\n<meta name=\"description\" content=\"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como usar fun\u00e7\u00f5es de pesquisa no Excel?\" \/>\n<meta property=\"og:description\" content=\"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/\" \/>\n<meta property=\"og:site_name\" content=\"Excel Advisor\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T11:44:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/\",\"name\":\"Como usar fun\u00e7\u00f5es de pesquisa no Excel?\",\"isPartOf\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png\",\"datePublished\":\"2023-10-15T12:42:55+00:00\",\"dateModified\":\"2023-12-06T11:44:07+00:00\",\"description\":\"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.\",\"breadcrumb\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage\",\"url\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/exceladvisor.org\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como usar fun\u00e7\u00f5es de pesquisa no excel?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#website\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"name\":\"Excel Advisor\",\"description\":\"O seu guia definitivo para dominar os dados!\",\"publisher\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#organization\",\"name\":\"Excel Advisor\",\"url\":\"https:\/\/exceladvisor.org\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"contentUrl\":\"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png\",\"width\":105,\"height\":36,\"caption\":\"Excel Advisor\"},\"image\":{\"@id\":\"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como usar fun\u00e7\u00f5es de pesquisa no Excel?","description":"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/","og_locale":"pt_PT","og_type":"article","og_title":"Como usar fun\u00e7\u00f5es de pesquisa no Excel?","og_description":"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.","og_url":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/","og_site_name":"Excel Advisor","article_modified_time":"2023-12-06T11:44:07+00:00","og_image":[{"url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/","url":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/","name":"Como usar fun\u00e7\u00f5es de pesquisa no Excel?","isPartOf":{"@id":"https:\/\/exceladvisor.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage"},"thumbnailUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png","datePublished":"2023-10-15T12:42:55+00:00","dateModified":"2023-12-06T11:44:07+00:00","description":"Neste artigo, listamos as 17 melhores fun\u00e7\u00f5es de pesquisa do Excel com exemplos.","breadcrumb":{"@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#primaryimage","url":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png","contentUrl":"https:\/\/exceladvisor.org\/wp-content\/uploads\/2023\/08\/exemple-de-fonction-dadresse-excel-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/exceladvisor.org\/pt\/funcoes-de-pesquisa-do-excel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/exceladvisor.org\/pt\/"},{"@type":"ListItem","position":2,"name":"Como usar fun\u00e7\u00f5es de pesquisa no excel?"}]},{"@type":"WebSite","@id":"https:\/\/exceladvisor.org\/pt\/#website","url":"https:\/\/exceladvisor.org\/pt\/","name":"Excel Advisor","description":"O seu guia definitivo para dominar os dados!","publisher":{"@id":"https:\/\/exceladvisor.org\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exceladvisor.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exceladvisor.org\/pt\/#organization","name":"Excel Advisor","url":"https:\/\/exceladvisor.org\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","contentUrl":"https:\/\/exceladvisor.org\/pt\/wp-content\/uploads\/2023\/12\/exceladvisor.org_.png","width":105,"height":36,"caption":"Excel Advisor"},"image":{"@id":"https:\/\/exceladvisor.org\/pt\/#\/schema\/logo\/image\/"}}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":1,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/640\/revisions"}],"predecessor-version":[{"id":1347,"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/pages\/640\/revisions\/1347"}],"wp:attachment":[{"href":"https:\/\/exceladvisor.org\/pt\/wp-json\/wp\/v2\/media?parent=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}